{"id":48051,"date":"2015-10-05T13:57:04","date_gmt":"2015-10-05T11:57:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-cibo-della-magna-grecia-e-il-mito-di-alarico-arrivano-ad-expo-2015\/"},"modified":"2023-01-17T12:39:41","modified_gmt":"2023-01-17T11:39:41","slug":"54010-il-cibo-della-magna-grecia-e-il-mito-di-alarico-arrivano-ad-expo-2015","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/54010-il-cibo-della-magna-grecia-e-il-mito-di-alarico-arrivano-ad-expo-2015\/","title":{"rendered":"Il cibo della Magna Grecia e il mito di Alarico arrivano ad Expo 2015"},"content":{"rendered":"<h4><strong>La Provincia di Cosenza porta ad Expo i tesori della sua terra tra dibattiti, degustazioni e\u00a0cooking show.<\/strong> <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MILANO &#8211; Punto di partenza \u00e8 un territorio ricco di\u00a0tradizione con una storia gastronomica che affonda le sue radici nell&#8217;antichit\u00e0 greca e romana.\u00a0Cos\u00ec lo show- cooking che vede all&#8217;opera lo straordinario chef Enzo Barbieri parte proprio\u00a0dalle ricette realizzate nella Magna Grecia dai suoi antichi colleghi, presentate in anteprima\u00a0assoluta. Ma la partecipazione della Provincia di Cosenza ad Expo \u00e8 anche l&#8217;occasione per\u00a0riscoprire l&#8217;intrico legato al tesoro perduto della tomba di Alarico. Infine si parler\u00e0, durante\u00a0una tavola rotonda, della <strong>Grande provincia italiana come centralit\u00e0 Mediterranea<\/strong>.\u00a0Il primo appuntamento \u00e8 per domani\u00a0alle 16,00 presso il padiglione KIP per un\u00a0pomeriggio dedicato alla scoperta di Cosenza con l&#8217;incontro dal titolo: \u201cCosenza, la grande\u00a0provincia italiana. Il valore dell&#8217;identit\u00e0 tra produzioni di qualit\u00e0, mito, storia e leggenda\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00a0confronto prendono parte: Mario Occhiuto, Presidente Provincia di Cosenza, Roberto\u00a0Burdese, Presidente Onorario Slow Food Italia, Franco Iseppi, Presidente Touring club\u00a0italiano, Giliola Barbero, Universit\u00e0 Cattolica di Milano, Zhu Yun Wa, \u00a0Senatore Repubblica\u00a0Popolare Cinese, Presidente esecutivo dell\u2019associazione Cina-Italia di Shanghai, Vice\u00a0Presidente esecutivo per il padiglione China Corporate United Pavillon.\u00a0<strong>Lo chef Enzo Barbieri presenter\u00e0 i classici strozzapreti, rivelando la loro ascendenza pi\u00f9\u00a0antica<\/strong>. Nel deliziarci con le sue ricette storiche il grande cuoco di Altomonte ricorda come la\u00a0Lucanica era gi\u00e0 menzionata dallo storico latino Marco Terenzio Varrone, che ne riportava\u00a0l&#8217;origine proprio ai Lucani. Ma i riferimenti storico-letterari che pongono\u00a0la cucina cosentina al centro della gastronomia italiana sono numerosissimi, da Virgilio che\u00a0cita il latte delle mucche del territorio magico per la realizzazione dei formaggi, al celebre vino\u00a0Balbino, fino all&#8217;uso dei fichi.<\/p>\n<p>&nbsp;<\/p>\n<p>Un altro dei piatti previsti durante il cooking show \u00e8\u00a0<strong>l&#8217;involtino di capocollo fresco di suino nero di Calabria, con caciocavallo podolico Silano e fichi\u00a0dottati di Altomonte secchi<\/strong>. Con la sua partecipazione ad Expo, la Provincia di Cosenza vuole\u00a0anche ricordare uno dei momenti pi\u00f9 misteriosi della sua storia. L&#8217;epopea di Alarico il re dei\u00a0Goti, che mise a ferro e fuoco Roma nel 410, si concluse infatti proprio in Calabria dove si\u00a0ammal\u00f2 e mor\u00ec. Il luogo della sua sepoltura \u00e8 ancora un mistero e fervono i tentativi per\u00a0individuarlo. L&#8217;appuntamento poi prevede\u00a0anche un momento di confronto in cui la Provincia di\u00a0Cosenza (tra le provincie pi\u00f9 grandi d&#8217;Italia) ricorda quanto \u00e8 fondamentale il ruolo delle\u00a0grandi province nelle politiche di sviluppo sostenibile. \u00c8 una terra di qualit\u00e0 ambientale egastronomica, di storia e di miti, ma anche un territorio che pu\u00f2, per la \u00a0sua complessit\u00e0 e la\u00a0variet\u00e0, rappresentare la sintesi delle eccellenze italiane.\u00a0Lo stand della Provincia ad Expo rester\u00e0 allestito per tutta la settimana, con degustazioni e\u00a0incontri con le aziende locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Provincia di Cosenza porta ad Expo i tesori della sua terra tra dibattiti, degustazioni e\u00a0cooking show.<\/p>\n","protected":false},"author":22,"featured_media":48052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34],"tags":[],"class_list":["post-48051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48051"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48052"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}