{"id":4828,"date":"2012-10-03T06:42:34","date_gmt":"2012-10-03T04:42:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4828"},"modified":"2023-01-17T13:38:08","modified_gmt":"2023-01-17T12:38:08","slug":"1689-precari-sanita-sindacati-annunciano-mobilitazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1689-precari-sanita-sindacati-annunciano-mobilitazione\/","title":{"rendered":"Precari sanit\u00e0: sindacati annunciano mobilitazione"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\"><strong>REGGIO CALABRIA<\/strong> -Quanto sta accadendo presso gli OO.RR. di Reggio Calabria nei confronti del personale medico e sanitario cosiddetto \u201cprecario\u201d, pur trovandoci di fronte a lavoratrici e lavoratori che da anni garantiscono il funzionamento di essenziali servizi e prestazioni nell\u2019ambito della struttura ospedaliera,<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\"> in alcuni casi da oltre dieci anni, ha portato le OO.SS. FP CGIL, CISL FP, UIL FPL a indire l\u2019assemblea del personale interessato che si \u00e8 svolta il 2 ottobre presso la sala Spinelli.<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">L\u2019Assemblea particolarmente partecipata, vista la situazione in atto e le motivazioni che l\u2019hanno resa necessaria, ha registrato da parte delle lavoratrici e dei lavoratori interessati un forte e pressante appello a sostegno delle OO.SS. perch\u00e9 si facciano carico nei confronti dei livelli istituzionali coinvolti di affrontare e portare a soluzione la difficile condizione di \u201cprecariet\u00e0\u201d permanente, che interessa circa 200 lavoratrici e lavoratori nella sola realt\u00e0 di Reggio.<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">I rappresentanti sindacali intervenuti: Franco Manunta per la FP CGIL, Antonio Bevacqua per la CISL FP, Nuccio Azzar\u00e0 per la UIL FPL, hanno ricordato che, proprio su richiesta delle OO.SS:, \u00e8 in atto il confronto a livello regionale per la definizione di modalit\u00e0 risolutive della problematica del \u201cprecariato\u201d presso le strutture sanitarie della regione, che interessano circa 2000 lavoratrici e lavoratori la cui eventuale espulsione bloccherebbe l\u2019erogazione di essenziali prestazioni, di fatto paralizzando il servizio sanitario pubblico in Calabria.<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Il prossimo 8 ottobre si terr\u00e0 un nuovo incontro regionale sulla questione e sar\u00e0 quella l\u2019occasione per valutare la volont\u00e0 o meno dei vertici della Regione Calabria, di portare a soluzione la ormai annosa questione del \u201cprecariato\u201d ed \u00e8 proprio a sostegno dell\u2019iniziativa sindacale che l\u2019assemblea, al termine dei lavori ha approvato il seguente documento:<\/span><br style=\"margin: 0px; padding: 0px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\" \/><span style=\"font-size: 12px; line-height: 18.649999618530273px; text-align: justify; background-color: #ffffff;\">Le OO.SS. FP CGIL \u2013 CISL FP \u2013 UIL FPL e il personale medico-sanitario a vario titolo \u201cprecario\u201d degli OO.RR. di Reggio Calabria riuniti in assemblea a seguito dei provvedimenti \u201cprovocatori\u201d di preavviso di cessazione di lavoro nonch\u00e9 dal venir meno del personale a tempo determinato, nel quadro delle iniziative di mobilitazione gi\u00e0 preannunciate al tavolo regionale di confronto dalle OO.SS. CGIL-CISL-UIL lo scorso 24 settembre, dichiarano la mobilitazione del personale, preannunciando sin d\u2019ora che, se il prossimo 8 ottobre dal confronto regione Calabria \u2013 OO.SS. non dovessero venire risposte adeguate ad affrontare e condurre a soluzione la questione \u201cprecari\u201d nella sanit\u00e0 pubblica calabrese, si assumeranno ulteriori iniziative di protesta.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA -Quanto sta accadendo presso gli OO.RR. di Reggio Calabria nei confronti del personale medico e sanitario cosiddetto \u201cprecario\u201d, pur trovandoci di fronte a lavoratrici e lavoratori che da anni garantiscono il funzionamento di essenziali servizi e prestazioni nell\u2019ambito della struttura ospedaliera,<\/p>\n","protected":false},"author":22,"featured_media":4829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-4828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4828"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4829"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}