{"id":48309,"date":"2015-10-13T09:36:56","date_gmt":"2015-10-13T07:36:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/quattro-albanesi-fermati-nellentroterra-calabrese-con-un-chilo-e-mezzo-di-eroina\/"},"modified":"2023-01-17T12:39:57","modified_gmt":"2023-01-17T11:39:57","slug":"55247-quattro-albanesi-fermati-nellentroterra-calabrese-con-un-chilo-e-mezzo-di-eroina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/55247-quattro-albanesi-fermati-nellentroterra-calabrese-con-un-chilo-e-mezzo-di-eroina\/","title":{"rendered":"Quattro albanesi fermati nell&#8217;entroterra calabrese con un chilo e mezzo di eroina"},"content":{"rendered":"<h4>Si tratta di eroina purissima di cui ad ora non si conosce la provenienza.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">GIRIFALCO (CZ) &#8211; Quattro persone sono state arrestate dai carabinieri delle Compagnie di Catanzaro e Girifalco nel corso di un blitz avvenuto a Girifalco nel pomeriggio di ieri. I quattro, tutti di nazionalit\u00e0 albanese, sono stati sorpresi con 1,5 chilogrammi di eroina purissima. L&#8217;operazione \u00e8 scattata all&#8217;ingresso del paese, quando i militari del Norm delle due Compagnie hanno bloccato due autovetture sulle quali viaggiavano i quattro malviventi. La successiva perquisizione personale e veicolare ha permesso di rinvenire lo stupefacente nell&#8217;autovettura. Al momento non si conoscono ulteriori particolari, visto che le indagini sono tutt&#8217;ora in corso.\u00a0Dall\u2019operazione Gentlemen scattata nel cosentino lo scorso mese di Febbraio che port\u00f2 a 33 fermi \u00e8 emersa l\u2019esistenza di una fitta rete di narcotrafficanti internazionali in grado di movimentare grossi quantitativi di marijuana dall\u2019Albania verso l\u2019Italia, avvalendosi di vettori marittimi dell\u2019organizzazione, nonch\u00e9 di cocaina ed eroina, mediante l\u2019impiego di automezzi modificati nella struttura al fine di ricavarne appositi vani funzionali all\u2019occultamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta di eroina purissima di cui ad ora non si conosce la provenienza.<\/p>\n","protected":false},"author":22,"featured_media":48310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-48309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48309"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48310"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}