{"id":48351,"date":"2015-10-14T10:42:02","date_gmt":"2015-10-14T08:42:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/avanza-sette-mesi-di-stipendi-lavoratore-depresso-va-in-coma\/"},"modified":"2023-01-17T12:40:01","modified_gmt":"2023-01-17T11:40:01","slug":"55398-avanza-sette-mesi-di-stipendi-lavoratore-depresso-va-in-coma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/55398-avanza-sette-mesi-di-stipendi-lavoratore-depresso-va-in-coma\/","title":{"rendered":"Avanza sette mesi di stipendi, lavoratore depresso finisce in coma"},"content":{"rendered":"<h4>Uno dei quaranta dipendenti della Fondazione Terina \u00e8 stato ricoverato in terapia intensiva presso l&#8217;ospedale Pugliese di Catanzaro.\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">LAMEZIA TERME &#8211; L&#8217;uomo, residente a San Mango d&#8217;Aquino non riceve il proprio salario da sette mesi e pare soffrisse da qualche tempo di una forte depressione. Ieri i suoi familiari lo hanno ritrovato in casa privo di sensi e trasportato d&#8217;urgenza in ospedale. Il lavoratore \u00e8 ora in coma farmacologico. La Fondazione Terina ente subregionale che si occupa di ricerca negli anni ha accumulato debiti tali da non consentire neanche il pagamento dei propri dipendenti pur godendo di finanziamenti pubblici. <strong>Il pi\u00f9 cospicuo negli ultimi anni riguarda un progetto che ha permesso alla Terina di incassare dallo Stato ben 14 milioni di euro.<\/strong> \u201cApprendo con amarezza e preoccupazione &#8211; scrive\u00a0Mimmo Gianturco consigliere comunale di Lamezia Terme &#8211; del tragico episodio accaduto ad uno dei lavoratori della Fondazione Terina, ricoverato in terapia intensiva a causa di un malessere acutizzato per motivi personali da individuare anche nei problemi economici relativi al mancato pagamento di sette mensilit\u00e0 lavorative. A lui e a tutti i lavoratori della fonazione va la mia piena solidariet\u00e0 e vicinanza. Il 30 giugno scorso ho portato la mia solidariet\u00e0 alla manifestazione di protesta organizzata dai lavoratori per sensibilizzare la Regione Calabria su questo annoso problema. Dopo diversi mesi, non avendo i lavoratori ricevuto n\u00e9 garanzie n\u00e9 soluzioni, porteremo in Consiglio Comunale questa vicenda. Nonostante il Comune di Lamezia Terme non abbia nessuna competenza su questa vicenda, \u00e8 giusto che, essendo l&#8217;unico ente in House della Regione Calabria sul nostro territorio, la politica locale se ne occupi\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno dei quaranta dipendenti della Fondazione Terina \u00e8 stato ricoverato in terapia intensiva presso l&#8217;ospedale Pugliese di Catanzaro.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":48352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-48351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48351"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48352"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}