{"id":48450,"date":"2015-10-17T05:23:40","date_gmt":"2015-10-17T03:23:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestrato-centro-di-accoglienza-per-minori-stranieri-condizioni-inadeguate\/"},"modified":"2023-01-17T12:40:07","modified_gmt":"2023-01-17T11:40:07","slug":"55778-sequestrato-centro-di-accoglienza-per-minori-stranieri-condizioni-inadeguate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/55778-sequestrato-centro-di-accoglienza-per-minori-stranieri-condizioni-inadeguate\/","title":{"rendered":"Sequestrato centro di accoglienza per minori stranieri, condizioni inadeguate"},"content":{"rendered":"<h4><strong>La Procura di Vibo Valentia ha sequestrato il Parco agricolo di Maierato in uso ad un&#8217;associazione costituita allo scopo di procedere all&#8217;accoglienza dei minori stranieri non accompagnati arrivati a Vibo nel corso degli ultimi sbarchi.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>MAIERATO (VV) &#8211; Una struttura adibita all&#8217;accoglienza dei minori recentemente sbarcati a Vibo ma priva dei minimi requisiti di sicurezza ed igienico-sanitari \u00e8 stata sottoposta a sequestro giudiziario previo trasferimento dei 31 minori ospitati all&#8217;interno. Si tratta di un capannone industriale di circa 900 metri quadrati, con una palazzina annessa inizialmente votata ad ufficio, le cui camere sono state all&#8217;occorrenza arredate con mobilio essenziale. Carenti i servizi sanitari ed esigua la presenza di bagni e docce in numero assolutamente inadeguato rispetto a quello delle presenze. Diverse le violazioni amministrative e penali riscontrate dagli investigatori, fra tutte quella relativa alla normativa antincendio. Sulla vicenda sono in corso approfondimenti da parte della Sezione Polizia giudiziaria della Procura, unitamente ai Nas di Catanzaro, al fine di verificare la regolarita&#8217; amministrativa delle procedure utilizzate nell&#8217;affidamento ai vari sodalizi che da circa un anno vengono costituite per la gestione dell&#8217;accoglienza di migranti nel Vibonese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procura di Vibo Valentia ha sequestrato il Parco agricolo di Maierato in uso ad un&#8217;associazione costituita allo scopo di procedere all&#8217;accoglienza dei minori stranieri non accompagnati arrivati a Vibo nel corso degli ultimi sbarchi.<\/p>\n","protected":false},"author":22,"featured_media":48451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-48450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48450"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48451"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}