{"id":48678,"date":"2015-10-24T06:44:09","date_gmt":"2015-10-24T04:44:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sanita-il-consiglio-comunale-di-cosenza-chiede-in-un-documento-la-fine-della-gestione-commissariale\/"},"modified":"2023-01-17T12:40:22","modified_gmt":"2023-01-17T11:40:22","slug":"56855-sanita-il-consiglio-comunale-di-cosenza-chiede-in-un-documento-la-fine-della-gestione-commissariale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/56855-sanita-il-consiglio-comunale-di-cosenza-chiede-in-un-documento-la-fine-della-gestione-commissariale\/","title":{"rendered":"Sanit\u00e0: Consiglio comunale di Cosenza chiede in un documento la fine del commissariamento del settore"},"content":{"rendered":"<h4>Anche Oliverio ha preso parte alla riunione del Consiglio comunale di Cosenza ed ha ribadito: &#8220;il nuovo ospedale di Cosenza \u00e8 una priorit\u00e0&#8221;<\/h4>\n<p><!--more--><\/p>\n<p>COSENZA &#8211; Il Consiglio comunale di Cosenza, riunito sotto la presidenza di Luca Morrone, ha discusso oggi, quale unico punto all\u2019ordine del Giorno, la situazione della sanit\u00e0 a Cosenza e in provincia per la \u201cpenalizzazione subita rispetto alle scelte dell\u2019ufficio del Commissario per l\u2019attuazione del piano di rientro dal debito sanitario e della Regione Calabria\u201d.\u00a0Erano presenti alla seduta aperta il Presidente della Regione Calabria Mario Oliverio, il Presidente dell\u2019Ordine dei Medici di Cosenza Eugenio Corcione, il Direttore dell\u2019azienda Ospedaliera di Cosenza Mario Veltri.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-56858 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/10\/oliverio-e-occhiuto.jpg\" alt=\"oliverio e occhiuto\" width=\"325\" height=\"217\" title=\"\"><\/p>\n<p>Dopo un dibattito molto partecipato, al termine del quale hanno tirato le somme il sindaco Mario Occhiuto ed il Governatore Oliverio, il Consiglio comunale ha approvato con 13 voti (l\u2019unico contrario quello del consigliere Giuseppe Mazzuca) un documento elaborato dal consigliere Enzo Paolini nel quale, \u201cconsiderato che le funzioni del Commissario ad acta sono finalizzate ad un ben preciso atto amministrativo e cio\u00e8 il <strong>rientro dal debito sanitario<\/strong>; preso atto che la fase commissariale dura invece da oltre sei anni e che, in conseguenza di ci\u00f2, i cittadini sono stati di fatto, e per troppo tempo, espropriati del loro diritto a governare le scelte di politica sanitaria attraverso i loro rappresentanti democraticamente eletti; considerati altres\u00ec come<strong> obiettivi primari perseguibili attraverso scelte di governo di politica sanitaria, il miglioramento della organizzazione del servizio, la ristrutturazione quali-quantitativa dei servizi di pronto soccorso-emergenza; la costruzione di una efficace ed efficiente rete territoriale, l&#8217;abbattimento delle liste d&#8217;attesa e la diminuzione della migrazione sanitaria, la lotta agli sprechi ed infine l&#8217;avvio del processo di realizzazione del nuovo ospedale della citt\u00e0.<\/strong><\/p>\n<p>Il Consiglio Comunale di Cosenza chiede al Governo nazionale di dichiarare al pi\u00f9 presto la cessazione della fase commissariale e la restituzione al Consiglio ed alla Giunta regionale di prerogative, diritti e funzioni che loro competono per il governo del servizio sanitario regionale\u201d.\u00a0<span style=\"line-height: 1.5;\">Il documento dispone infine che la mozione venga trasmessa a tutti i deputati e senatori eletti in Calabria, al Ministro della Salute, al Ministro dell&#8217;Economia e Finanze, al Presidente del Consiglio dei Ministri.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche Oliverio ha preso parte alla riunione del Consiglio comunale di Cosenza ed ha ribadito: &#8220;il nuovo ospedale di Cosenza \u00e8 una priorit\u00e0&#8221;<\/p>\n","protected":false},"author":22,"featured_media":45099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-48678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48678"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45099"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}