{"id":4868,"date":"2012-10-03T13:10:58","date_gmt":"2012-10-03T11:10:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4868"},"modified":"2023-01-17T13:38:10","modified_gmt":"2023-01-17T12:38:10","slug":"1710-bloccato-parco-eolico-azienda-cinese-contro-obama","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1710-bloccato-parco-eolico-azienda-cinese-contro-obama\/","title":{"rendered":"Bloccato parco eolico, azienda cinese contro Obama"},"content":{"rendered":"<p style=\"text-align: justify;\">(AGI) &nbsp;&#8211; Una piccola azienda di proprieta&#8217; cinese ha citato in giudizio il presidente Usa, Barack Obama, che la scorsa settimana ha bloccato<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">un acquisto dell&#8217;azienda su suolo statunitense adducendo motivi di sicurezza militare: l&#8217;azienda, proprieta&#8217; di due cittadini cinesi, vorrebbe costruire un parco eolico vicino a una base navale statunitense. La denuncia e&#8217; stata presentata dalla Ralls Corporation, filiale negli Usa della cinese Sany, dinanzi al Tribunale del distretto di Washington: la tesi e&#8217; che il presidente si sia spinto oltre le sue prerogative costituzionali e non abbia presentato prove. Gia&#8217; lo scorso fine settimana, il responsabile dell&#8217;ufficio legale della Sany (il maggiore fabbricante di macchinari cinese) aveva accusato Obama di aver preso la decisione per conquistare voti in campagna elettorale; ma l&#8217;impressione e&#8217; che l&#8217;azienda abbia sottovalutato i sospetti americani sulle mire cinesi. Obama ha bloccato la settimana scorsa l&#8217;acquisto di quattro pale eoliche nell&#8217;Oregon (Usa) da parte della Ralls, sostenendo che l&#8217;operazione rappresenta una minaccia potenziale per la sicurezza nazionale: l&#8217;impianto e&#8217; vicino a un sito militare, utilizzato per testare i droni senza pilota e dove i jet effettuano manovre di addestramento ad altissima velocita&#8217; e a quota molto bassa. E&#8217; la prima volta in 22 anni che un presidente Usa applica in questo modo la Legge di Sicurezza in Difesa, che assegna al capo dello Stato il potere di veto su operazioni di aziende straniere. Tra l&#8217;altro, i vertici aziendali fanno notare che le pale eoliche anche nel passato erano di proprieta&#8217; straniera (la Ralls le ha acquistate dalla greca Terna), ma all&#8217;epoca Washington non lo considerava evidentemente un problema. Insomma, secondo l&#8217;agenzia Xinhua, la decisione di Obama e&#8217; dovuta alla campagna elettorale perche&#8217; il Partito Repubblicano ha utilizzato come uno dei suoi principali argomenti contro l&#8217;attuale presidenza la mancanza di fermezza di fronte al dilagante potere cinese. Le possibilita&#8217; di spuntarla pero&#8217; per i cinesi sono poche, considerata l&#8217;ampia autorita&#8217; del presidente su questioni di sicurezza nazionale e il fatto che la magistratura americana si allinea spesso con l&#8217;esecutivo su questi argomenti.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(AGI) &nbsp;&#8211; Una piccola azienda di proprieta&#8217; cinese ha citato in giudizio il presidente Usa, Barack Obama, che la scorsa settimana ha bloccato<\/p>\n","protected":false},"author":22,"featured_media":4869,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,22,5],"tags":[],"class_list":["post-4868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dal-mondo","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4868"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4869"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}