{"id":48815,"date":"2015-10-28T11:56:36","date_gmt":"2015-10-28T10:56:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/altroconsumo-calabria-e-google-per-promuovere-la-sicurezza-online-con-vivi-internet-al-sicuro-audio-intervista\/"},"modified":"2023-01-17T12:40:33","modified_gmt":"2023-01-17T11:40:33","slug":"57494-altroconsumo-calabria-e-google-per-promuovere-la-sicurezza-online-con-vivi-internet-al-sicuro-audio-intervista","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/57494-altroconsumo-calabria-e-google-per-promuovere-la-sicurezza-online-con-vivi-internet-al-sicuro-audio-intervista\/","title":{"rendered":"Altroconsumo Calabria e Google per promuovere la sicurezza online con &#8220;Vivi Internet, al sicuro&#8221; (AUDIO INTERVISTA)"},"content":{"rendered":"<h4><strong>Dal 15 ottobre \u00e8 partita la campagna per aiutare i calabresi a familiarizzare con internet.<\/strong><\/h4>\n<p><!--more--><br \/>\nCOSENZA &#8211; <strong>Google e Altroconsumo<\/strong> hanno attivato in sinergia la campagna divulgativa <strong>\u201cVivi internet, al sicuro\u201d<\/strong>, nata per <strong>avvicinare al web i cittadini consumatori-utenti<\/strong> che ancora non hanno familiarit\u00e0 con lo strumento, e offrire a tutti consigli semplici ed efficaci per utilizzarlo in piena sicurezza. &#8220;Oggi infatti, il digital divide &#8211; spiega Pietro Vitelli, responsabile di Altroconsumo Regione Calabria &#8211; soprattutto nelle regioni meridionali quale la Calabria, ovvero il divario tra chi ha accesso alle tecnologie dell&#8217;informazione e chi ne \u00e8 escluso, rappresenta una sfida. <strong>Circa un terzo della popolazione italiana (31%) non \u00e8 mai entrata in Rete e solo il 59% vi naviga con regolarit\u00e0<\/strong>. Forte il gap, non solo per la Calabria ma, in generale a livello nazionale rispetto agli altri paesi per quanto riguarda la connettivit\u00e0 e le competenze digitali: su 28 stati dell\u2019Unione Europea, l\u2019Italia si classifica 25\u00b0 in termini di DESI (Digital Economy and Society Index])&#8221;.<\/p>\n<p>&#8220;Un altro ostacolo rilevante allo sviluppo di una economia digitale &#8211; spiega ancora Vitelli &#8211; \u00e8 rappresentato dalla<strong> mancanza di fiducia degli utenti<\/strong>, ancora fortemente restii <strong>ad affidarsi al web<\/strong> per gestire le attivit\u00e0 quotidiane (ad esempio, solo il 42% di italiani si avvale di servizi bancari online e il 35% fa acquisiti sul web. Tutti questi elementi rallentano la diffusione della digitalizzazione e la nascita di una economia digitale&#8221;.<\/p>\n<div id=\"attachment_57495\" style=\"width: 266px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/10\/vitelli.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-57495\" class=\" wp-image-57495\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/10\/vitelli-224x280.jpg\" alt=\"Pietro Vitellli, responsabile Altroconsumo Calabria\" width=\"256\" height=\"299\" title=\"\"><\/a><p id=\"caption-attachment-57495\" class=\"wp-caption-text\">Pietro Vitellli, responsabile Altroconsumo Calabria<\/p><\/div>\n<p>La collaborazione tra Altroconsumo e Google nasce per superare queste difficolt\u00e0 ed \u00e8 frutto della partnership sono il sito<span style=\"color: #0000ff;\"><strong><a href=\"http:\/\/www.altroconsumo.it\/vivinternet\/\" target=\"_blank\" rel=\"noopener\"> altroconsumo.it\/vivinternet<\/a><\/strong><\/span>, e la guida \u201cVivi internet, al sicuro\u201d, entrambi rivolti al grande pubblico e pensati per favorire la digitalizzazione e fornire gli strumenti necessari a navigare sul web in sicurezza.\u00a0<strong>Il sito affronta il tema della sicurezza online<\/strong> in tutti i suoi aspetti e fornisce approfondimenti tematici basati sui consigli del Centro per la Sicurezza Online e dello strumento Account Personale di Google:<\/p>\n<p>&#8211; <strong>Sicurezza<\/strong>: per navigare con tranquillit\u00e0, sia sul motore di ricerca sia sulle altre pagine online.<br \/>\n&#8211; <strong>Privacy<\/strong>: per proteggere la riservatezza dei propri dati personali seguendo pochi, semplici consigli.<br \/>\n&#8211; <strong>Smartphone<\/strong>: le precauzioni da prendere per evitare che, in caso di smarrimento del cellulare, un estraneo possa accedere alle nostre informazioni.<br \/>\n&#8211; <strong>Password<\/strong>: semplici accorgimenti per ottenere la massima sicurezza quando usiamo i nostri account.<br \/>\n&#8211; <strong>Browser<\/strong>: la scelta di un browser aggiornato permette agli utenti di navigare al passo con l\u2019evoluzione degli standard Internet, sfruttando tutte le nuove funzionalit\u00e0 offerte dal web.<br \/>\n&#8211; <strong>Connessione<\/strong>: per riconoscere le connessioni sicure e per impedire che i dati della carta di credito o del conto corrente siano accessibili a soggetti non autorizzati.<br \/>\n&#8211; <strong>Protezione<\/strong>: indicazioni per una protezione ancora pi\u00f9 efficace dei propri dati.<\/p>\n<p>La guida, fa sapere <strong>Pietro Vitelli<\/strong> che questa mattina ha parlato della campagna ai microfoni di<strong> Rlb Radioattiva<\/strong>, pu\u00f2 essere richiesta gratuitamente attraverso il sito, raccoglie indicazioni estremamente pratiche per avvicinarsi al mondo di internet con la giusta consapevolezza. Pagine ricche di esempi, che invitano a scoprire le potenzialit\u00e0 della rete e a fare di internet un alleato affidabile.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><\/p>\n<p>[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/10\/Pietro-Vitelli-Altroconsumo-Calabria.mp3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 15 ottobre \u00e8 partita la campagna per aiutare i calabresi a familiarizzare con internet.<\/p>\n","protected":false},"author":19,"featured_media":48816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-48815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48815"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48816"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}