{"id":48863,"date":"2015-10-29T15:32:28","date_gmt":"2015-10-29T14:32:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/studente-dellindustriale-di-cosenza-inventa-dispositivo-per-controllare-casa-dal-cellulare\/"},"modified":"2023-01-17T12:40:37","modified_gmt":"2023-01-17T11:40:37","slug":"57701-studente-dellindustriale-di-cosenza-inventa-dispositivo-per-controllare-casa-dal-cellulare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/57701-studente-dellindustriale-di-cosenza-inventa-dispositivo-per-controllare-casa-dal-cellulare\/","title":{"rendered":"Studente dell&#8217;industriale di Cosenza inventa dispositivo per &#8216;controllare&#8217; casa dal cellulare"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><strong>L\u2019Istituto Tecnico Industriale &#8216;Monaco&#8217; di Cosenza<\/strong>\u00a0primo classificato al Concorso di Elettronica, indetto da Elettrolab alla Fiera dell\u2019Illuminotronica di Padova.<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211;\u00a0Si rinnovano i trofei all\u2019Istituto Tecnico Industriale di via Popilia.\u00a0<strong>Il giovane studente Curcio Battista della classe V A Elettronica, coniugando perfettamente competenze, capacit\u00e0 e conoscenze, guidato dal tutor Annunciato Imbrogno, si \u00e8 classificato al primo posto nella kermesse che ha visto competere diversi istituti tecnici a livello nazionale<\/strong> alla Fiera di Padova nel padiglione dell\u2019\u00eclluminotronica che si \u00e8 tenuto dal 6 all\u20198 Ottobre 2015.\u00a0Il progetto, illustrato attraverso un video, ha mostrato la sua valenza nell\u2019aver con un intuito geniale dell\u2019alunno gi\u00e0 dimostrato in altre occasioni, progettato e costruito un dispositivo di telecontrollo con telefonia mobile per la domotica assistiva.\u00a0Il prototipo permette di visionare la casa di una persona anziana mediante i sensori collegati a una centralina che invia sms in caso si registrassero anomalie o alterazioni o mancato funzionamento di un qualsiasi dispositivo.\u00a0Ad esempio, se \u00e8 rilevata una fuga di gas, dall\u2019esterno si pu\u00f2 comandare con una chiamata la centralina digitando un apposito codice che aziona la valvola di spegnimento del gas.\u00a0Un\u2019altra funzione progettata dall\u2019allievo, consiste nell&#8217;attivare elettrodomestici, riscaldamenti, sempre attraverso l\u2019uso di cellulari e senza bisogno di computer.\u00a0Nel caso in cui l\u2019anziano sia colto da un malore improvviso, ha la possibilit\u00e0 di allertare immediatamente con un semplice pulsante i familiari o chi pu\u00f2 aiutarlo.<\/p>\n<p style=\"text-align: right;\">In foto\u00a0il giovane studente Battista Curcio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Istituto Tecnico Industriale &#8216;Monaco&#8217; di Cosenza\u00a0primo classificato al Concorso di Elettronica, indetto da Elettrolab alla Fiera dell\u2019Illuminotronica di Padova.<\/p>\n","protected":false},"author":22,"featured_media":48864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,61],"tags":[],"class_list":["post-48863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-tecnologia-e-internet"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=48863"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/48863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48864"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=48863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=48863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=48863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}