{"id":49385,"date":"2015-11-14T06:30:37","date_gmt":"2015-11-14T05:30:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presentato-un-progetto-che-aiuta-i-ragazzi-nella-scelta-della-scuola-superiore\/"},"modified":"2023-01-17T12:41:15","modified_gmt":"2023-01-17T11:41:15","slug":"60400-presentato-un-progetto-che-aiuta-i-ragazzi-nella-scelta-della-scuola-superiore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/60400-presentato-un-progetto-che-aiuta-i-ragazzi-nella-scelta-della-scuola-superiore\/","title":{"rendered":"Presentato un progetto che aiuta i ragazzi nella scelta della scuola superiore"},"content":{"rendered":"<h4><strong>Lo scorso marted\u00ec 10 novembre, l\u2019associazione Inform@ti ha presentato il progetto\u00a0\u201cOrientare al Successo\u201d nella splendida cornice della Biblioteca Nazionale di Cosenza.\u00a0<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; Con questo progetto si intendono attivare e condividere una serie di strumenti\u00a0innovativi al fine di supportare l\u2019orientamento alla scelta degli studi superiori nei giovani in\u00a0et\u00e0 tra 12 e 13 anni, affinch\u00e9 tali scelte siano coerenti con le reali esigenze del mercato del\u00a0lavoro, le attitudini e le prospettive di vita di queste giovanissime generazioni.\u00a0Gli studenti delle scuole medie coinvolte, \u201cZumbini\u201d di Cosenza e \u201cR. Pisano\u201d di Pedace, ovvero\u00a060 selezionati su 200 domande di adesione presentate, <strong>saranno guidati attraverso una serie di\u00a0laboratori didattici all\u2019interno delle scuole superiori<\/strong> coinvolte al fine di poter testare la loro\u00a0offerta didattica ed extracurriculare. Al termine del percorso che durer\u00e0 8 mesi, i giovani\u00a0studenti avranno realizzato anche un cortometraggio al fine di comunicare i risultati ottenuti.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">A fare gli onori di casa la Direttrice della Biblioteca Nazionale, Elvira Graziani, che ha posto\u00a0l\u2019accento sull\u2019importanza della cultura e della costruzione di una relazione tra i giovani al fine di creare uomini e\u00a0donne di successo, ma soprattutto cittadini responsabili.\u00a0Il dibattito, coordinato da Anna Laura Orrico, cofounder di Talent Garden Cosenza, partner del\u00a0progetto, ha visto protagonisti il Direttore Generale dell\u2019Associazione Informati, Dott. Raffaele\u00a0Cesario, e i Presidi degli Istituti Partner: la Prof.ssa Maria Gabriella Greco, Dirigente Scolastico\u00a0Istituto Comprensivo Cosenza Zumbini, il Prof. Andrea Codispoti, Dirigente Scolastico\u00a0Istituto Comprensivo \u201cR. Pisano\u201d di Pedace, l\u2019Ing. Antonio Iaconianni, Dirigente Scolastico\u00a0Liceo Classico \u201cB. Telesio\u201d di Cosenza, accompagnato dal Prof. Lombardo che seguir\u00e0 la\u00a0realizzazione del cortometraggio finale previsto dal progetto; il Prof. Giorgio Clarizio,\u00a0Dirigente Scolastico dell\u2019Istituto Istruzione Superiore \u201cSerra-Quasimodo\u201d di Cosenza, e l\u2019Avv.\u00a0Armando Cardei,Presidente Associazione In.form@ti.<\/p>\n<p>&nbsp;<\/p>\n<p>Al centro della tavola rotonda le riflessioni dei giovani\u00a0studenti riportate dai Tweet realizzati durante un primo laboratorio. Tweet che hanno\u00a0sottolineato quanto nell\u2019orientamento verso il successo siano importanti valori come<strong> la\u00a0condivisione, il lavoro di squadra e la capacit\u00e0 di impegnarsi per il bene comune<\/strong>.\u00a0A completare il quadro l\u2019intervento di Valentina Pezzi (19 anni), giovane Vice Presidente\u00a0dell\u2019associazione Pandosia eARTh che ha raccontato quanto sia stato importante nella\u00a0riflessione sugli studi da perseguire, partecipare ad un progetto (Giovani&amp;FuturoComune) che\u00a0ha visto lei e il suo gruppo confrontarsi con imprenditori e professionisti, e infine cimentarsi\u00a0in uno startup di impresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo scorso marted\u00ec 10 novembre, l\u2019associazione Inform@ti ha presentato il progetto\u00a0\u201cOrientare al Successo\u201d nella splendida cornice della Biblioteca Nazionale di Cosenza.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":49386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,41,34],"tags":[],"class_list":["post-49385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/49385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=49385"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/49385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/49386"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=49385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=49385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=49385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}