{"id":49754,"date":"2015-11-24T09:36:32","date_gmt":"2015-11-24T08:36:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ospedale-privato-a-rende-il-principato-attende-il-parere-di-oliverio\/"},"modified":"2023-01-17T12:41:43","modified_gmt":"2023-01-17T11:41:43","slug":"62085-ospedale-privato-a-rende-il-principato-attende-il-parere-di-oliverio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/62085-ospedale-privato-a-rende-il-principato-attende-il-parere-di-oliverio\/","title":{"rendered":"Ospedale privato a Rende, il &#8216;Principato&#8217; attende il parere di Oliverio"},"content":{"rendered":"<h4>La Giunta Manna vuole capire quale sia la posizione del Presidente della Regione prima di deliberare l&#8217;avvio della conferenza dei servizi.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE &#8211; Nuovo rinvio del punto all&#8217;ordine del giorno relativo alla costruzione degli Ospedali Riuniti iGreco a Rende. Ancora in fase di stallo l&#8217;apertura della conferenza dei servizi che dovr\u00e0 valutare il progetto proposto dalla holding di Cariati che intende creare nell&#8217;area di Sant&#8217;Agostino un struttura che ospiter\u00e0 i reparti delle cliniche Madonnina, Madonna della Catena e Sacro Cuore. La sospensione del consiglio comunale \u00e8 stata decisa in attesa di accogliere il parere del Presidente della Regione Mario Oliverio.<strong> I consiglieri di maggioranza avevano infatti chiesto un incontro con il governatore che avverr\u00e0 presumibilmente in settimana, poi, Luned\u00ec 30 Novembre si voter\u00e0.<\/strong> Intanto la societ\u00e0 civile \u00e8 gi\u00e0 mobilitata contro il progetto definito &#8216;antagonista al nuovo ospedale pubblico dell&#8217;Area Urbana&#8217; che dovrebbe sorgere nella stessa area che costeggia viale Magna Grecia. I comitati PrendoCasa, CAT Villaggio Europa, comitato di quartiere Piazza Piccola ieri presenti in consiglio comunale hanno espresso il proprio dissenso in merito al progetto proposto dal gruppo iGreco che dovrebbe costare\u00a0circa 30 milioni di euro.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Ci sfugge &#8211; scrivono in una nota &#8211; la logica di un progetto politico\/amministrativo che porti alla costruzione di due Ospedali, uno pubblico e uno privato (solo nella propriet\u00e0 visto che sar\u00e0 convenzionato e quindi finanziato con fondi regionali) nello stesso territorio. Partiamo da un assunto fondamentale: non si specula sulla salute. Non possiamo che essere contrari al fatto che il diritto alla salute possa essere posto sul mercato, che oltre al costo del servizio ci possa essere un di pi\u00f9 che remuneri il profitto aziendale&#8221;. <strong>I comitati esortano il sindaco Manna ad abbandonare l&#8217;entusiasmo mostrato nei confronti delle proposte della famiglia Greco.<\/strong> &#8220;Rinunci, per il bene della collettivit\u00e0 a questa operazione, rinunci all&#8217;ulteriore cementificazione di un territorio gi\u00e0 mortificato, prenda le distanze dalla stretta mortale di una classe politica indecente e di un&#8217;imprenditoria spregiudicata e predatoria interessata solo al proprio tornaconto. A noi &#8211; sottolineano gli attivisti &#8211; non servono nuove strutture, serve che si tuteli il nostro diritto alla salute dalla speculazione privata, che si potenzino i servizi gratuiti esistenti ed aumenti la qualit\u00e0 delle prestazioni insieme all&#8217;accessibilit\u00e0 per tutti&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Giunta Manna vuole capire quale sia la posizione del Presidente della Regione prima di deliberare l&#8217;avvio della conferenza dei servizi.<\/p>\n","protected":false},"author":22,"featured_media":49755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-49754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/49754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=49754"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/49754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/49755"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=49754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=49754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=49754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}