{"id":49913,"date":"2015-11-28T09:27:09","date_gmt":"2015-11-28T08:27:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/oggi-presentazione-di-un-libro-che-racconta-le-dimore-storiche-del-centro-storico-cosentino\/"},"modified":"2023-01-17T12:41:52","modified_gmt":"2023-01-17T11:41:52","slug":"62864-oggi-presentazione-di-un-libro-che-racconta-le-dimore-storiche-del-centro-storico-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/62864-oggi-presentazione-di-un-libro-che-racconta-le-dimore-storiche-del-centro-storico-cosentino\/","title":{"rendered":"Oggi presentazione di un libro che racconta le dimore storiche del centro storico cosentino"},"content":{"rendered":"<h4><strong>Il volume si intitola \u201cI palazzi raccontano\u2026 guida alle dimore\u00a0storiche dell\u2019antica Cosenza\u201d, \u00e8 curato da Francesco Paolo Dodaro\u00a0ed edito dalla Luigi Pellegrini Editore.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; L\u2019evento \u00e8 promosso dalla Fondazione Attilio e Elena\u00a0Giuliani Onlus in collaborazione con il Leo Club Cosenza &#8220;Marlena\u00a0Parisi&#8221;. La presentazione del libro\u00a0sar\u00e0 preceduta da una visita guidata a cura dell\u2019autore nei palazzi\u00a0oggetto del libro e partir\u00e0 alle 16.30 da piazza XV Marzo (Palazzo\u00a0della Provincia), passeggiando lungo Corso Telesio in direzione di\u00a0Villa Rendano.\u00a0Concluso questo interessante tour, alle 19.00, sar\u00e0 la volta dei\u00a0saluti e della presentazione del libro a Villa\u00a0Rendano, sede della Fondazione Giuliani.\u00a0Il volume di Francesco Paolo Dodaro rappresenta una nuova\u00a0versione del testo realizzato tre anni fa dai ragazzi del club sui\u00a0palazzi storici della citt\u00e0 di Cosenza, <strong>arricchito di ulteriori notizie\u00a0storiche e presentato in una nuova veste grafica<\/strong>.\u00a0L&#8217;evento \u00e8 stato realizzato con il patrocinio dei Lions Club Cosenza\u00a0Host, Castello Svevo e Rovito Sila Grande, e rientra nel novero\u00a0delle iniziative relative al progetto distrettuale Leo Citizen &#8211; Territori\u00a0in movimento, un progetto avente come fine quello di individuare un\u00a0bene o una tematica territoriale da valorizzare in collaborazione con\u00a0gli enti locali e altre associazioni. A tal proposito durante la\u00a0presentazione sar\u00e0 possibile acquistare delle copie del libro il cui\u00a0ricavato sar\u00e0 interamente devoluto al restauro di un busto ligneo\u00a0settecentesco, individuato dal club come bene da valorizzare.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/11\/loc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-62875\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/11\/loc.jpg\" alt=\"loc\" width=\"568\" height=\"803\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il volume si intitola \u201cI palazzi raccontano\u2026 guida alle dimore\u00a0storiche dell\u2019antica Cosenza\u201d, \u00e8 curato da Francesco Paolo Dodaro\u00a0ed edito dalla Luigi Pellegrini Editore.<\/p>\n","protected":false},"author":22,"featured_media":49914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25],"tags":[],"class_list":["post-49913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/49913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=49913"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/49913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/49914"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=49913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=49913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=49913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}