{"id":50107,"date":"2015-12-03T14:26:20","date_gmt":"2015-12-03T13:26:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/e-in-libreria-il-secondo-volume-della-collana-la-citta-dei-cittadini-della-fondazione-giuliani-onlus\/"},"modified":"2023-01-17T12:42:03","modified_gmt":"2023-01-17T11:42:03","slug":"63840-e-in-libreria-il-secondo-volume-della-collana-la-citta-dei-cittadini-della-fondazione-giuliani-onlus","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/63840-e-in-libreria-il-secondo-volume-della-collana-la-citta-dei-cittadini-della-fondazione-giuliani-onlus\/","title":{"rendered":"E&#8217; in libreria il secondo volume della collana &#8221;La citt\u00e0 dei cittadini&#8221; della Fondazione Giuliani Onlus"},"content":{"rendered":"<h4>Il testo verr\u00e0 presentato questa sera alle 17,30 presso Villa Rendano, a Cosenza.<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211;\u00a0&#8221;Cosenza-Rende, una leggenda metropolitana. Un nuovo modello di mobilit\u00e0\u00a0nell\u2019area urbana&#8221;, di Fabio Melia e Ennio Forte, edito dalla Fondazione \u201cAttilio e Elena Giuliani\u00a0Onlus\u201d,\u00a0diretta dall\u2019avv. Francesco\u00a0Pellegrini.\u00a0Il primo volume, edito nei mesi scorsi, \u00e8 stato &#8221;La\u00a0Grande Cosenza&#8221;.\u00a0Il nuovo libro si avvale dell\u2019introduzione di Bruno Manfellotto, per anni direttore del settimanale\u00a0L\u2019Espresso, il quale significativamente intitola il suo scritto \u201cTrent\u2019anni di inettitudine\u201d, perch\u00e9 il\u00a0sogno di dotare l\u2019area urbana di Cosenza risale addirittura al 1982 ma a tutt\u2019oggi non si vede una\u00a0via di sbocco ad una situazione che \u00e8 costata oltre 4 milioni di euro. Fabio Melia, giornalista della\u00a0redazione cosentina della Gazzetta del Sud, ricostruisce puntigliosamente tutti i passaggi,\u00a0burocratici e politici, che hanno condotto a questo stato di stallo, con amministrazioni comunali,\u00a0ministri, sottosegretari, sindaci, dirigenti regionali, che non riescono a venire a capo della\u00a0realizzazione di un indispensabile collegamento efficace e veloce tra il centro di Cosenza e Rende,\u00a0compresa ovviamente l\u2019Universit\u00e0 della Calabria.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Manfellotto la definisce \u00abuna storia esemplare [\u2026]. Perch\u00e9 delle due l\u2019una: o la metropolitana\u00a0leggera \u00e8 solo un\u2019idea balzana, un orpello inutile o peggio solo un pozzo senza fondo di euri nel\u00a0quale \u00e8 pronta a tuffarsi la criminalit\u00e0, e allora \u00e8 stato un delitto perderci trent\u2019anni di tempo\u00a0prezioso; oppure \u00e8 davvero un\u2019infrastruttura fondamentale per il futuro di Cosenza e della sua\u00a0provincia, e allora bisognerebbe indignarsi per gli anni sprecati e non lasciare che la questione\u00a0anneghi nelle beghe locali\u00bb.\u00a0Il secondo saggio del volume \u00e8 di Ennio Forte, gi\u00e0 professore ordinario di Economia di trasporti e\u00a0della logistica nell\u2019Universit\u00e0 Federico II di Napoli dove attualmente \u00e8 docente incaricato della\u00a0stessa disciplina. Il prof. Forte dedica il suo scritto di 180 pagine al sistema metropolitano dell\u2019area Cosenza-Rende\u00a0analizzando, con decine di tabelle e mappe, tutta la situazione infrastrutturale e della mobilit\u00e0 del\u00a0territorio, per fornire \u00abutili indicazioni alla migliore fattibilit\u00e0 e fruizione del futuro sistema\u00a0integrato dei trasporti pubblici dell\u2019area, sia su ferro che su gomma\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/12\/loc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63858\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/12\/loc.jpg\" alt=\"loc\" width=\"232\" height=\"640\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il testo verr\u00e0 presentato questa sera alle 17,30 presso Villa Rendano, a Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":48469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25],"tags":[],"class_list":["post-50107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=50107"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/48469"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=50107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=50107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=50107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}