{"id":50432,"date":"2015-12-12T15:08:34","date_gmt":"2015-12-12T14:08:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/un-domenica-di-buone-feste-cosentine-si-parte-dallafrica-programma-eventi\/"},"modified":"2023-01-17T12:42:29","modified_gmt":"2023-01-17T11:42:29","slug":"65131-un-domenica-di-buone-feste-cosentine-si-parte-dallafrica-programma-eventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/65131-un-domenica-di-buone-feste-cosentine-si-parte-dallafrica-programma-eventi\/","title":{"rendered":"Un domenica di &#8216;Buone feste cosentine&#8217;, si parte dall&#8217;Africa (PROGRAMMA EVENTI)"},"content":{"rendered":"<h4>La cultura musicale africana protagonista della domenica di \u201cBuone Feste cosentine\u201d.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211;\u00a0E\u2019 la cultura musicale africana la protagonista dell\u2019evento di punta della giornata di Domenica 13 dicembre del cartellone di \u201cBuone Feste cosentine\u201d, il tradizionale e nutrito programma di eventi natalizi e di fine anno.<strong>\u00a0Alle 18,00 sul palco allestito in Piazza Kennedy salir\u00e0 il percussionista ivoriano Moussa Ndao, protagonista dello spettacolo \u201cAfrica Djembefolalou\u201d.\u00a0<\/strong>L\u2019idea dello spettacolo nasce dalla conoscenza, che risale a due anni fa, di alcuni giovani cosentini con il Maestro Moussa Ndao. Da questa conoscenza \u00e8 scaturito l\u2019impegno comune di portare la cultura musicale africana in tutta la Calabria. Grazie soprattutto a Moussa Ndao che, trasferitosi a Cosenza, ha concentrato le sue energie, istituendo Laboratori di Percussioni e Danze Africane sul territorio. Uno spettacolo di Percussioni e Danza Africana, incentrato su diversi ritmi appartenenti alla cultura musicale dell\u2019Africa Occidentale. Nello spettacolo saranno utilizzati diversi strumenti, portatori delle tradizioni africane, dal Djembe al Doum Doum al Tam\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Negli altri appuntamenti del programma domenicale di \u201cBuone Feste cosentine\u201d spicca il doppio omaggio a Dante Alighieri che la citt\u00e0 di Cosenza ha inteso tributare al Sommo Poeta, in occasione delle celebrazioni del 750\u00b0 anniversario della nascita. Nella Sala \u201cQuintieri\u201d del Teatro \u201cRendano\u201d, <strong>alle 20,30, l\u2019associazione culturale \u201cCosenza Autentica\u201d propone il concerto dell\u2019ensemble barocco che porta lo stesso nome del sodalizio culturale, \u201cCosenza Autentica\u201d<\/strong>, dal titolo \u201cPoesia e Musica: cantate del barocco italiano\u201d. L\u2019ingresso al concerto sar\u00e0 libero e gratuito. Sempre a cura di \u201cCosenza Autentica\u201d, insieme all\u2019Associazione \u201cMystica Calabria\u201d prosegue, fino al 18 dicembre, alla Biblioteca Civica, la collettiva d\u2019arte contemporanea di 21 opere di artisti calabresi che si sono ispirate alle cantiche della Divina Commedia, dal suggestivo titolo dantesco \u201cL\u2019amor che move il sole e l\u2019altre stelle\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L&#8217;esposizione della Biblioteca civica sar\u00e0 visitabile da luned\u00ec a venerd\u00ec dalle 09.30 alle 12.00.\u00a0E sempre in omaggio a Dante prosegue anche domenica 13 dicembre al <strong>Chiostro di San Domenico la mostra \u201cLuoghi e Personaggi della Divina Commedia nei dipinti di Mariateresa Aiello<\/strong>\u201d, promossa dal Comitato \u201cDante Alighieri\u201d di Cosenza di cui \u00e8 Presidente Maria Cristina Parise Martirano.\u00a0L\u2019esposizione comprende diciannove dipinti dell\u2019artista cosentina Maria Teresa Aiello realizzati appositamente per accompagnare, di volta in volta, tutto il percorso di un anno di lecturae Dantis.\u00a0Sempre domenica 13 dicembre alla Biblioteca civica (alle 18,30, nella sala \u201cSalfi\u201d) per la rassegna cinematografica, proiezione del film \u201cStoker\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Gli appuntamenti per gli spettatori pi\u00f9 piccoli di \u201cBuone Feste cosentine\u201d prevedono, sempre per domani, al Villaggio degli Elfi, <strong>nella Villa Vecchia, (dalle 10,30 alle 13,00 e dalle 16,00 alle 19,00) l\u2019iniziativa \u201cBiscottando Natale &#8211; Il dolce Natale dei bambini\u201d e, alle ore 18,00 al teatro \u201cMorelli\u201d, per la rassegna \u201cFamiglie a teatro\u201d,<\/strong> la rappresentazione della celebre fiaba \u201cLa bella addormentata\u201d a cura della compagnia teatrale \u201cFlorian Metateatro\u201d. Si replica luned\u00ec 14 dicembre, alle ore 10,00 al Teatro dell\u2019Acquario per la rassegna \u201cScuole a teatro\u201d.\u00a0Sempre luned\u00ec 14 dicembre, ancora spazio ai bambini al Villaggio degli Elfi, in Villa Vecchia, dove, a partire dalle 15,30 \u00e8 in programma il laboratorio di riuso e riciclo, a cura di Ricicrea e la proiezione del film \u201cLa principessa e il ranocchio\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Il programma di luned\u00ec 14 dicembre di \u201cBuone Feste cosentine\u201d include, inoltre, alle ore 16,30, nella Chiesa di San Domenico, a cura del Convegno di Cultura \u201cMaria Cristina di Savoia\u201d la lectio magistralis di Mario Bozzo, Presidente della Fondazione Carical, sugli inni sacri di Alessandro Manzoni. La lectio sar\u00e0 preceduta da una presentazione della Presidente del Convegno di Cultura \u201cMaria Cristina di Savoia\u201d Angela Gatto.Nell\u2019ambito dell\u2019iniziativa, previsto anche <strong>il Concerto di Natale per organo, a cura del Conservatorio \u201cStanislao Giacomantonio\u201d<\/strong>.\u00a0E sempre in tema musicale, alle ore 17,00 di luned\u00ec 14 dicembre, nella Sala \u201cQuintieri\u201d del \u201cRendano\u201d, concerto del pianista Francesco Perri, promosso dall\u2019Associazione \u201cMariano Turano\u201d in occasione del \u201cMemorial Attilio Perri\u201d.\u00a0U<strong>ltimo appuntamento musicale di luned\u00ec, alle 18,00, in Piazza Kennedy il concerto del Trio Swing.\u00a0<\/strong>Si ricorda, infine, che alle ore 17,30, al Santuario del SS. Crocifisso, \u00e8 in programma l\u2019apertura della Porta Santa che dar\u00e0 l\u2019avvio al Giubileo della Misericordia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cultura musicale africana protagonista della domenica di \u201cBuone Feste cosentine\u201d.<\/p>\n","protected":false},"author":22,"featured_media":50433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-50432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=50432"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/50433"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=50432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=50432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=50432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}