{"id":50567,"date":"2015-12-16T15:35:23","date_gmt":"2015-12-16T14:35:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/clan-rango-abbruzzese-chiesti-500-anni-di-carcere-per-la-cosca-cosentina\/"},"modified":"2023-01-17T12:42:38","modified_gmt":"2023-01-17T11:42:38","slug":"65732-clan-rango-abbruzzese-chiesti-500-anni-di-carcere-per-la-cosca-cosentina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/65732-clan-rango-abbruzzese-chiesti-500-anni-di-carcere-per-la-cosca-cosentina\/","title":{"rendered":"Clan Rango-Abbruzzese, chiesti 500 anni di carcere per la cosca cosentina"},"content":{"rendered":"<h4>Per il presunto boss del sodalizio Maurizio Rango chiesta la pena dell&#8217;ergastolo.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">CATANZARO &#8211; Il sostituto procuratore della Dda di Catanzaro, Pierpaolo Bruni, ha chiesto condanne per quasi 500 anni di carcere nei confronti dei 35 imputati che hanno scelto il rito abbreviato nell&#8217;ambito dell&#8217;inchiesta &#8220;Nuova famiglia&#8221; sul clan cosentino Rango-Abbruzzese. Tra loro appaino anche il collaboratore di giustizia Foggetti e Sottile. Il pm nell&#8217;udienza di oggi ha depositato una requisitoria &#8220;informatica&#8221; con link diretti agli atti dell&#8217;indagine che consentir\u00e0 al gup, con un semplice click, una piu&#8217; agevole consultazione del fascicolo. Per Maurizio Rango, considerato il capo dell&#8217;organizzazione, il pm ha chiesto l&#8217;ergastolo. L<strong>&#8216;imputato oltre che di associazione mafiosa deve rispondere anche dell&#8217;omicidio e dell&#8217;occultamento del cadavere di Luca Bruni, il cui scheletro venne ritrovato in un casolare nei pressi di Orto Matera.<\/strong> Il clan di &#8216;ndrangheta, sempre secondo la tesi dell&#8217;accusa, controllerebbe il racket delle estorsioni, avrebbe acquisito (anche con l&#8217;uso di armi) la gestione e controllo di attivit\u00e0, appalti pubblici ed avrebbe occupato abusivamente alloggi popolari per poi rivenderli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per il presunto boss del sodalizio Maurizio Rango chiesta la pena dell&#8217;ergastolo.<\/p>\n","protected":false},"author":22,"featured_media":50568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-50567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=50567"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/50568"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=50567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=50567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=50567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}