{"id":5075,"date":"2012-10-05T12:19:15","date_gmt":"2012-10-05T10:19:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=5075"},"modified":"2023-01-17T13:38:23","modified_gmt":"2023-01-17T12:38:23","slug":"1818-pallamano-crotone-si-lavora-per-il-futuro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1818-pallamano-crotone-si-lavora-per-il-futuro\/","title":{"rendered":"Pallamano Crotone: si lavora per il futuro"},"content":{"rendered":"<p lang=\"it-IT\" style=\"text-align: justify;\">La Pallamano Crotone continua a lavorare e profondere impegno sul campo, ma ancora non ha nessuna notizia in merito al prossimo campionato.<\/p>\n<p>  <!--more-->  <\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Tutto \u00e8 ancora sospeso ed intanto \u00e8&nbsp;un\u2019altra settimana.&nbsp;trascorsa<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Da notizie ufficiose, a differenza di pochi giorni fa, sembra che anche la squadra di Reggio Calabria si sia iscritta al campionato di serie B. Ma cos\u00ec come hanno fatto Crotone e Terranova anche Reggio Calabria ha chiesto di disputare il campionato fuori regione aggregandosi per\u00f2 al girone siciliano. Aumenta dunque l\u2019incertezza. Apparentemente potrebbe sembrare che tutto stia andando in una direzione corretta perch\u00e9 le squadre hanno chiesto di propria spontanea volont\u00e0 di disputare un campionato di un\u2019altra regione, ma il regolamento della serie B che lo consente va un po\u2019 contro. Ogni Federazione regionale ha infatti il diritto secondo il suddetto regolamento di avere un promozione dalla serie B alla serie A2. Questo potrebbe essere un ostacolo per Crotone e Terranova a far parte del girone campano &#8211; pugliese e per il Reggio Calabria a parte di quello siciliano. Le intenzioni per\u00f2 sono chiare, le squadre calabresi non vogliono disputare un campionato composto da tre sole squadre e le altre hanno dato il proprio assenso ad \u201cospitare\u201d le formazioni calabresi. La Federazione potrebbe rinunciare alla promozione che gli spetta se organizza un campionato solo regionale e concedere il via libera rinunciando per\u00f2 alla sicurezza di avere una squadra in serie A2. Le diplomazie sono al lavoro e devono trovare al pi\u00f9 presto la soluzione ideale per tutti perch\u00e9 i campionati devono iniziare altrimenti rischierebbero poi di finire troppo tardi.<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Intanto le trattative fra la societ\u00e0 e quello che dovrebbe essere in nuovo sponsor sono a buon punto, il tutto dovrebbe essere definito a breve, l\u2019annuncio dovrebbe arrivare nei prossimi giorni.<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">La squadra continua a lavorare sul parquet. Nella settimana che sta per chiudersi si \u00e8 lavorato sul potenziamento delle braccia ed inoltre il tecnico Massimo Cusato ha fatto svolgere i primi esercizi con i palloni. Nella prossima settimana si continuer\u00e0 su questa linea per poi passare alla tecnica personale ed alla tattica, il tutto in attesa di notizie da parte della Federazione sul prossimo campionato.<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">&nbsp;<\/p>\n<p lang=\"it-IT\" style=\"text-align: justify;\">Strill.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pallamano Crotone continua a lavorare e profondere impegno sul campo, ma ancora non ha nessuna notizia in merito al prossimo campionato.<\/p>\n","protected":false},"author":22,"featured_media":5076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-5075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=5075"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/5075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/5076"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=5075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=5075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=5075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}