{"id":50837,"date":"2015-12-26T05:55:29","date_gmt":"2015-12-26T04:55:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/dalla-jamaica-a-cosenza-the-skatalites-domani-allauditorium-popolare\/"},"modified":"2023-01-17T12:43:06","modified_gmt":"2023-01-17T11:43:06","slug":"66955-dalla-jamaica-a-cosenza-the-skatalites-domani-allauditorium-popolare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/66955-dalla-jamaica-a-cosenza-the-skatalites-domani-allauditorium-popolare\/","title":{"rendered":"Dalla Jamaica a Cosenza, &#8216;The Skatalites&#8217; domani all&#8217;Auditorium Popolare"},"content":{"rendered":"<h4>La storica band giamaicana si esibir\u00e0 domani nell&#8217;area delle ex officine ferroviarie.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211;\u00a0Direttamente dalla Jamaica, terra madre della reggae music, la band &#8220;The Skatalites&#8221; rigorosamente live nella citt\u00e0 dei bruzi per coronare un Natale all&#8217;insegna dello Ska-Reggae. Domani sera, Domenica 27 a partire dalle 23.00 presso l&#8217;Auditorium Popolare di Cosenza, nell&#8217;area delle ex officine ferroviarie tra Viale Parco e via Popilia musica\u00a0e allegrie chiuderanno il week end natalizio. La manifestazione Reggaembre giunta ormai alla sua nona edizione si aprir\u00e0 con l&#8217;esibizione della band cosentina dei Ganja Social Club. Poi l&#8217;attesissimo live degli Skatalites per poi continuare la serata in allegria con la dancehall dei Mujina Crew.\u00a0A<strong>gli Skatalites, si ricorda, va riconosciuto il merito di aver per primi dato un nome a questa musica in levare.<\/strong> Attivi sin dagli anni Sessanta sono tuttora attivissimi\u00a0anche se nella formazione non sono presenti alcuni dei membri fondatori ormai deceduti.\u00a0Tra i musicisti che hanno fatto parte della formazione Don Drummond, Tommy McCook, Rolando Alphonso, Lloyd Brevett, Lloyd Knibb, Lester Sterling, Jah Jerry Haynes, Jackie Mittoo, Johnny Moore, Jackie Opel and Doreen Shaffer. Le canzoni pi\u00f9 famose degli Skatalites comprendono &#8220;Guns of Navarone&#8221;, &#8220;Confucious&#8221;, &#8220;Christine Keiler&#8221;, &#8220;Malcom X&#8221;, &#8220;Eastern Standard Time&#8221; e &#8220;Phoenix City&#8221;. Un appuntamento da non perdere per tutti gli amanti dello Ska &#8211; Reggae.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La storica band giamaicana si esibir\u00e0 domani nell&#8217;area delle ex officine ferroviarie.<\/p>\n","protected":false},"author":22,"featured_media":50838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-50837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=50837"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/50838"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=50837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=50837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=50837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}