{"id":50918,"date":"2015-12-29T09:46:23","date_gmt":"2015-12-29T08:46:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-tradizionale-sagra-del-cinghiale-di-campana-si-rinnova-sulle-note-dei-kaliserna\/"},"modified":"2023-01-17T12:43:13","modified_gmt":"2023-01-17T11:43:13","slug":"67329-la-tradizionale-sagra-del-cinghiale-di-campana-si-rinnova-sulle-note-dei-kaliserna","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/67329-la-tradizionale-sagra-del-cinghiale-di-campana-si-rinnova-sulle-note-dei-kaliserna\/","title":{"rendered":"La tradizionale sagra del cinghiale di Campana si rinnova sulle note dei Kaliserna"},"content":{"rendered":"<h4><strong>Con\u00a0il ritmo frenetico e le sonorit\u00e0 mediterranee dei Kaliserna nasce\u00a0la prima edizione della &#8221;Cinghialata&#8221;.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">CAMPANA (CS) &#8211; Una festa dal sapore antico, con degustazioni di piatti tipici a base di carne di cinghiale. La manifestazione si terr\u00e0 questa sera alle\u00a019,00 in Piazza Sant\u2019Antonio accompagnata dall\u2019esibizione live del gruppo di musicisti campanesi.\u00a0A darne notizia \u00e8 il Sindaco Agostino Chiarello che invita tutto il territorio a cogliere questa occasione per arricchire le vacanze natalizie e di Capodanno, di identit\u00e0 e tradizioni autentiche, <strong>alla scoperta dei patrimoni custoditi nei nostri centri storici e nell\u2019entroterra<\/strong>.\u00a0L\u2019evento, organizzato dall\u2019associazione &#8216;Amici di Bacco&#8217; con il patrocinio del Comune e delle squadre di caccia del territorio di Campana, fa parte di un calendario ricco di iniziative natalizie previste nel Paese dell\u2019Elefante di Pietra.\u00a0L\u2019attesissima Cinghialata sar\u00e0 preceduta, alle 15,00 da una festa per bambini. Si terr\u00e0, infatti,<strong> uno spettacolo con cabaret e trampoliere per le vie del Paese<\/strong> a cura della Confraternita. Domani invece,\u00a0alle 20,00, la stessa Confraternita proporr\u00e0 il concerto di Cosimo Papandrea in Piazza Italia, nel cuore del centro storico.\u00a0Per festeggiare assieme l\u2019arrivo del nuovo anno, venerd\u00ec\u00a01 gennaio\u00a0in Piazza Santa Croce alle 15,30 \u00e8 previsto l\u2019arrivo di Babbo Natale, a cura dell\u2019associazione Amici di Bacco con il patrocinio del Comune.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con\u00a0il ritmo frenetico e le sonorit\u00e0 mediterranee dei Kaliserna nasce\u00a0la prima edizione della &#8221;Cinghialata&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":50919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-50918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=50918"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/50919"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=50918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=50918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=50918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}