{"id":50983,"date":"2016-01-02T09:27:25","date_gmt":"2016-01-02T08:27:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/buone-feste-cosentine-tanti-appuntamenti-per-il-primo-weekend-dellanno\/"},"modified":"2023-01-17T11:26:09","modified_gmt":"2023-01-17T10:26:09","slug":"67753-buone-feste-cosentine-tanti-appuntamenti-per-il-primo-weekend-dellanno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/67753-buone-feste-cosentine-tanti-appuntamenti-per-il-primo-weekend-dellanno\/","title":{"rendered":"Buone Feste Cosentine: tanti appuntamenti per il primo weekend dell&#8217;anno"},"content":{"rendered":"<h4><strong>Continua il programma di Buone Feste Cosentine organizzato dal Comune, tra Presepi viventi, cacce al tesoro e laboratori per bambini.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; Questo pomeriggio, alle 15.30, si parte da Piazza dei Bruzi con &#8220;I misteri di Alarico&#8221; III puntata, singolare &#8216;caccia al tesoro&#8217; guidata dal cantastorie William Gatto, un itinerario teatrale che segue le tracce lasciate in citt\u00e0 dal temerario Re dei Visigoti. Ad Alarico \u00e8 dedicato anche il mapping alla Confluenza (ore 18,30) che sar\u00e0 replicato anche domani.\u00a0Doppio appuntamento, oggi e domani, alle\u00a017,30, con il Presepe Vivente in piazzetta Toscano, organizzato come sempre del Comitato per la salvaguardia del centro storico.\u00a0Musica in piazza Kennedy questa sera alle 18,00 con &#8216;Christmas in loop&#8217;, e domani con Suoni e Rumori alle 11,30 e Francesca Guido alle 18,00. Al cinema Italia Teatro Tieri, questa sera alle 18,00, \u00e8 di scena il musical Pinocchio a cura di AVO, mentre al teatro Rendano alle\u00a020,15 appuntamento con il Concerto di Capodanno, nell&#8217;ambito della Stagione Lirico sinfonica. Una rinata Piazza Duomo ospita, alle 21,30, il quarto e ultimo appuntamento della rassegna musicale #tiricordipiazzaduomo, con la band dei Soul Pain.\u00a0Al Villaggio degli Elfi, prosegue per i bambini il laboratorio di percussioni e canti africani con il maestro Moussa Ndao.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L&#8217;intrattenimento musicale \u00e8 quello di Gigi &amp; Sabrina mentre la rassegna di cinema per ragazzi propone \u201cBelle &amp; Sebastien\u201d. Domani\u00a0invece si proietta \u201cThe Lego Movie\u201d. Domani alle 18,00 il Comitato Dante Alighieri organizza al Chiostro di San Domenico la Lectura Dantis \u201ca passi enti tyoccando un poco il futuro\u201d con Giada Armatore e Michele Lionetti, e le musiche di Mario Lino Stancati; nella sala Salfi della Biblioteca Civica si proietta \u201cIl segreto dei suoi occhi\u201d. La serata \u00e8 al cinema Italia Teatro Tieri prevede, alle 20,30, il concerto \u201cEra de Maggio\u201d, melodie napoletane del tempo antico. Protagonisti Annalisa D&#8217;Astoli al pianoforte, il mezzosoprano Sabrina De Rose e la voce narrante di Ciccio De Rose. Luned\u00ec 4 gennaio alla Casa delle Culture, si inaugura, alle 17,00, la mostra \u201cRadici\u201d a cura di Clara Silvana Fiore; alle 18,00 l&#8217;appuntamento quotidiano su piazza Kennedy \u00e8 con la musica del Duo Koin\u00e8; la sera al cinema teatro Italia Tieri, l&#8217;Associazione A.M.I.C.O. Volontario presenta lo spettacolo \u201cNatale al basilico tutti insieme appassionatamente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua il programma di Buone Feste Cosentine organizzato dal Comune, tra Presepi viventi, cacce al tesoro e laboratori per bambini.<\/p>\n","protected":false},"author":22,"featured_media":50984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-50983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=50983"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/50983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/50984"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=50983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=50983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=50983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}