{"id":51004,"date":"2016-01-03T07:07:04","date_gmt":"2016-01-03T06:07:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/le-cronache-di-nanna-domani-nuovamente-in-scena-a-cosenza\/"},"modified":"2023-01-17T11:26:11","modified_gmt":"2023-01-17T10:26:11","slug":"67832-le-cronache-di-nanna-domani-nuovamente-in-scena-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/67832-le-cronache-di-nanna-domani-nuovamente-in-scena-a-cosenza\/","title":{"rendered":"Le Cronache di Nanna, la parodia della cronaca cosentina domani nuovamente in scena"},"content":{"rendered":"<h4 class=\"p1\">&#8220;Nessun consigliere\u00a0regionale potr\u00e0 bloccare la rappresentazione e nessun cinghiale\u00a0potr\u00e0 intimare \u00abChiuda su c&#8230; i spettacolo!\u00bb&#8221;.<\/h4>\n<p><!--more--><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">COSENZA &#8211; Dopo i due sold out del 28 dicembre 2015 e del 2 gennaio 2016, le vecchie leggende continueranno a rivivere al Teatro dell&#8217;Acquario. Domani, Luned\u00ec\u00a04 gennaio 2016 alle 21.00 ritornano Le Cronache di Nanna.<strong> La terza replica dello spettacolo di\u00a0Nunzio Scalercio rinverdir\u00e0 fatti indicibili e incredibili storie, testimonianze di una Cosenza che ha bisogno di essere raccontata.<\/strong>\u00a0Le Cronache di Nanna stanno l\u00ec, lapidarie, a ricordarci chi siamo. Avendo consapevolezza che il futuro \u00e8 adesso. &#8220;Alla faccia dei venti di oscurantismo che aleggiano sull&#8217;occidente\u00a0calabro, &#8211; scrive in una nota lo staf fdell&#8217;organizzazione &#8211; pure il 4 gennaio 2016, al Teatro dell&#8217;Acquario rivivranno tutte\u00a0le vecchie leggende, puru chire ca paranu impossibili, pure ca un\u00a0preside di Rossano s&#8217;\u00e8 misu mienzu a rumpa a staccia. Ma diciami tu,\u00a0sinceramente: cu quale core negheresti al bambino Nunzietto di fare la\u00a0recita di fine anno davanti ai suoi cari (i cusentini toghi)?<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Il ritorno dal futuro (e no d&#8217;arrieti l&#8217;angolo, a cap\u00ec?) di Marti mcflai\u00a0non pu\u00f2 passare in sordina: va commentato. Va vagliato. Analizzato. Cos\u00ec\u00a0come la sparizione di politici regionali ormai raminghi dati per dispersi.\u00a0Tra gli ospiti della serata, saliranno sul palco il cantautore Antonello\u00a0Anzani, le attrici Francesca Florio e Annarita Lagan\u00e0, e il cugino di\u00a0primo grado del famosissimo politogo Edward Luttwak.\u00a0Nessun consigliere\u00a0regionale potr\u00e0 bloccare la rappresentazione e nessun cinghiale (ferito\u00a0&amp; non) potr\u00e0 intimare \u00abChiuda su cazzu i spettacolo!\u00bb.\u00a0Le leggende, per esistere, hanno bisogno di qualcuno disposto a\u00a0raccontarle&#8221;. Posto Unico 12 euro,<strong> ingresso gratuito per tutti quelli che trovano il tesoro di Alarico\u00a0senza droni, biglietto ridotto a universitari e a chi\u00a0assister\u00e0 allo spettacolo di ritorno da un divieto di dimora&#8221;.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Nessun consigliere\u00a0regionale potr\u00e0 bloccare la rappresentazione e nessun cinghiale\u00a0potr\u00e0 intimare \u00abChiuda su c&#8230; i spettacolo!\u00bb&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":51005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-51004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51004"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51005"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}