{"id":51041,"date":"2016-01-04T14:13:24","date_gmt":"2016-01-04T13:13:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sparano-e-rapinano-lufficio-postale-di-rende-circa-3000-euro-di-bottino\/"},"modified":"2023-01-17T11:26:15","modified_gmt":"2023-01-17T10:26:15","slug":"67998-sparano-e-rapinano-lufficio-postale-di-rende-circa-3000-euro-di-bottino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/67998-sparano-e-rapinano-lufficio-postale-di-rende-circa-3000-euro-di-bottino\/","title":{"rendered":"Rapinano l&#8217;Ufficio Postale di Rende, sparano e sottraggono circa 3000 euro di bottino"},"content":{"rendered":"<h4><strong>E&#8217; accaduto questa mattina all&#8217;Ufficio Postale di Roges di Rende.<\/strong><!--more--><\/h4>\n<p style=\"text-align: justify;\">RENDE (CS) &#8211;\u00a0Tre persone armate, con il volto coperto, hanno fatto irruzione nei locali dell&#8217;ufficio, minacciando i dipendenti. E&#8217; stato anche esploso un colpo di pistola, per fortuna senza conseguenze per i presenti. Il bottino della rapina \u00e8\u00a0di circa 3000 euro. Le indagini sul caso sono condotte dai\u00a0Carabinieri. La rapina di oggi \u00e8 la seconda in meno di un mese ai danni dell&#8217;ufficio postale di Roges.<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; accaduto questa mattina all&#8217;Ufficio Postale di Roges di Rende.<\/p>\n","protected":false},"author":22,"featured_media":51042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-51041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51041"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51042"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}