{"id":51236,"date":"2016-01-11T13:10:44","date_gmt":"2016-01-11T12:10:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tra-i-sindaci-piu-amati-ditalia-occhiuto-al-41-posto-insieme-a-falcomata\/"},"modified":"2023-01-17T11:26:39","modified_gmt":"2023-01-17T10:26:39","slug":"68820-tra-i-sindaci-piu-amati-ditalia-occhiuto-al-41-posto-insieme-a-falcomata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/68820-tra-i-sindaci-piu-amati-ditalia-occhiuto-al-41-posto-insieme-a-falcomata\/","title":{"rendered":"Tra i sindaci pi\u00f9 amati d&#8217;Italia Occhiuto al 41\u00b0 posto insieme a Falcomat\u00e0"},"content":{"rendered":"<h4>Il pi\u00f9 &#8216;odiato&#8217; d&#8217;Italia \u00e8 il primo cittadino di Crotone Peppino Vallone.\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; Il Sole 24 Ore ha pubblicato oggi la classifica dei sindaci pi\u00f9 amati d&#8217;Italia. Nessun primo cittadino calabrese \u00e8 riuscito a scalare la &#8216;graduatoria&#8217;. Anzi. Peppino Vallone, sindaco di Crotone, dopo aver perso oltre il 17% dei consensi dal giorno della sua nomina appare l&#8217;ultimo della lista. Mario Occhiuto e Giuseppe Falcomat\u00e0, rispettivamente seduti sugli scranni pi\u00f9 alti dei municipi di Cosenza e Reggio Calabria, sono i sindaci pi\u00f9 apprezzati in Calabria, ma non in Italia. Entrambi collocati\u00a0al 41\u00b0 posto della classifica portano con s\u00e9 un indice di gradimento pari al 55%. Tra loro per\u00f2 vi \u00e8 una netta differenza. <strong>Mentre Falcomat\u00e0 dal momento in cui \u00e8 stato eletto ha perso il 6% dei consensi, Occhiuto ne ha guadagnato l&#8217;1,7% nonostante i disagi creati a negozianti e residenti di piazza Bilotti con il progetto di riqualificazione e la discutibile gestione dello sgombero del campo nomadi di Vaglio Lise.<\/strong> A Vibo Valentia, il neosindaco Elio Costa si attesta al 63\u00b0 posto con un indice di gradimento pari al 52%. Il patron dei call center e di Sorical, Sergio Abramo, che per la terza volta siede sulla poltrona da sindaco a Catanzaro invece si \u00e8 posizionato all&#8217;89\u00b0 posto con il 48% di gradimento e la perdita del 2,6% dei consensi.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/217\">CLICCA QUI PER CONSULTARE LA LISTA DI TUTTE LE CITTA&#8217; ITALIANE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il pi\u00f9 &#8216;odiato&#8217; d&#8217;Italia \u00e8 il primo cittadino di Crotone Peppino Vallone.\u00a0<\/p>\n","protected":false},"author":18,"featured_media":51237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-51236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51236"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51237"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}