{"id":51372,"date":"2016-01-14T12:31:08","date_gmt":"2016-01-14T11:31:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestro-di-cocaina-a-roges-di-rende\/"},"modified":"2023-01-17T11:26:53","modified_gmt":"2023-01-17T10:26:53","slug":"69354-sequestro-di-cocaina-a-roges-di-rende","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/69354-sequestro-di-cocaina-a-roges-di-rende\/","title":{"rendered":"Sequestro di cocaina a Roges di Rende"},"content":{"rendered":"<h4>Cinquantunenne segnalato alle autorit\u00e0 competenti.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE &#8211; Nell&#8217;ambito dei servizi di controllo del territorio finalizzati al contrasto dello spaccio di sostanze stupefacente ieri in via Kennedy, a Roges di Rende, gli agenti della polizia di Stato hanno sequestrato cinque grammi di cocaina. Lo stupefacente, sigillato in un involucro, \u00e8 stato trovato a seguito di una perquisizione personale nelle disponibilit\u00e0 E. G., 51enne cosentino che aveva tentato invano di occultarlo. L&#8217;uomo, espletate le formalit\u00e0 di rito, \u00e8 stato segnalato alla locale Prefettura per detenzione di sostanze stupefacenti e sar\u00e0 sottoposto all&#8217;apposito programma terapeutico di recupero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinquantunenne segnalato alle autorit\u00e0 competenti.<\/p>\n","protected":false},"author":22,"featured_media":51373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-51372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51372"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51373"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}