{"id":51515,"date":"2016-01-18T18:00:11","date_gmt":"2016-01-18T17:00:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/meteo-domani-in-calabria-possibili-nevicate-a-quote-basse\/"},"modified":"2023-01-17T11:27:09","modified_gmt":"2023-01-17T10:27:09","slug":"69954-meteo-domani-in-calabria-possibili-nevicate-a-quote-basse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/69954-meteo-domani-in-calabria-possibili-nevicate-a-quote-basse\/","title":{"rendered":"Meteo, domani in Calabria possibili nevicate a quote basse"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><strong>Nuova allerta meteo della Protezione Civile.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">CATANZARO &#8211; \u201cDalle prossime ore una perturbazione di origine atlantica interesser\u00e0 la Sardegna per poi estendersi, nella giornata di domani, alle regioni meridionali con piogge e nevicate anche a bassa quota ed un rinforzo della ventilazione\u201d, informa la Protezione Civile. I fenomeni meteo, impattando sulle diverse aree del Paese, potrebbero determinare criticit\u00e0 idrogeologiche e idrauliche. <strong>L&#8217;avviso prevede dalla mattina di domani, marted\u00ec 19 gennaio, precipitazioni, anche a carattere di rovescio o temporale, su Basilicata, Calabria e Sicilia, che risulteranno a carattere nevoso al di sopra dei 300-500 metri sulla Basilicata e sulla Calabria settentrionale<\/strong>, al di sopra dei 500-800 metri sulla Calabria centro-meridionale e oltre gli 800 metri sulla Sicilia. Sulla base dei fenomeni previsti \u00e8 stata valutata per domani criticit\u00e0 gialla per rischio idrogeologico localizzato su Sicilia, Calabria, Molise, su gran parte della Puglia e su alcuni settori dell&#8217;Abruzzo.<\/p>\n<p style=\"text-align: justify;\">\nNella giornata di oggi le temperature sono rimaste molto rigide in tutta la regione, nonostante il cielo aperto e il sole che ha interessato quasi tutto il territorio. Il freddo gelido ha portato la neve su tutte le zone montane della regione, con una media di oltre 70 centimetri di coltre bianca che ha attecchito sul terreno. Le temperature hanno segnato una media di -10 gradi, ma nel corso della notte ci sono state punte fino a meno 18 gradi. La giornata ha registrato temperature sempre a ridosso dello zero quasi ovunque, con -1\/-3 gradi sui rilievi. Pochi i disagi, salvo quelli relativi alla circolazione stradale durante le prime ore del giorno ed in tarda serata, soprattutto per il rischio legato al ghiaccio.<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuova allerta meteo della Protezione Civile.<\/p>\n","protected":false},"author":22,"featured_media":51516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-51515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51515"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51516"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}