{"id":51517,"date":"2016-01-18T19:13:06","date_gmt":"2016-01-18T18:13:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/viabilita-nuovo-divieto-di-transito-tra-via-simonetta-e-via-rodota\/"},"modified":"2023-01-17T11:27:09","modified_gmt":"2023-01-17T10:27:09","slug":"69963-viabilita-nuovo-divieto-di-transito-tra-via-simonetta-e-via-rodota","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/69963-viabilita-nuovo-divieto-di-transito-tra-via-simonetta-e-via-rodota\/","title":{"rendered":"Viabilit\u00e0, nuovo divieto di transito tra via Simonetta e via Rodot\u00e0"},"content":{"rendered":"<h4><strong>Domani e mercoled\u00ec lavori sul lato Ovest di Piazza Bilotti.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; <strong>Per la giornata di domani, marted\u00ec 19 gennaio, e per quella di mercoled\u00ec 20 gennaio, \u00e8 stato istituito a Cosenza il divieto di transito, dalle ore 9,00 alle ore 16,00, nel tratto di Piazza Bilotti compreso tra via Simonetta e via Rodot\u00e0<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Lo ha stabilito, con un\u2019apposita ordinanza, il Comando della Polizia Municipale, a seguito della richiesta della ditta \u201cBilotti Parking\u201d, che sta eseguendo i lavori di riqualificazione e rifunzionalizzazione di piazza Bilotti e che domani e mercoled\u00ec dovr\u00e0 effettuare dei lavori sul lato Ovest della stessa piazza.<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani e mercoled\u00ec lavori sul lato Ovest di Piazza Bilotti.<\/p>\n","protected":false},"author":22,"featured_media":51518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-51517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51517"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51518"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}