{"id":51687,"date":"2016-01-22T14:42:50","date_gmt":"2016-01-22T13:42:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/al-rendano-debutta-una-tosca-che-unisce-tradizione-e-innovazione\/"},"modified":"2023-01-17T11:27:29","modified_gmt":"2023-01-17T10:27:29","slug":"70684-al-rendano-debutta-una-tosca-che-unisce-tradizione-e-innovazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/70684-al-rendano-debutta-una-tosca-che-unisce-tradizione-e-innovazione\/","title":{"rendered":"Al Rendano &#8221;debutta&#8221; una Tosca che unisce tradizione e innovazione"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><strong>L\u2019allestimento, concepito appositamente per la stagione lirico- sinfonica del Teatro Rendano, prevede videomapping e altre innovazioni che abbattono la \u201cquarta\u00a0parete\u201d.\u00a0<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; La \u201cTosca\u201d debutta questa sera, alle 20,15, sul palco del teatro di tradizione cosentino, firmata da Antonello Palombi, nome importante della lirica italiana e molto conosciuto come tenore, una delle voci italiane pi\u00f9 apprezzate in\u00a0tutto il mondo, spesso ospite al Teatro alla Scala di Milano o al\u00a0Metropolitan di New York. \u00a0Se da un lato l\u2019allestimento si presenta molto rispettoso dei canoni\u00a0abituali della tradizione operistica, dall\u2019altro sposa le nuove tecnologie, ricorrendo alle <strong>videoproiezioni<\/strong> e coinvolgendo nell\u2019azione scenica la stessa\u00a0platea, con l\u2019effetto di accorciare le distanze con il palcoscenico e\u00a0gli artisti ed <strong>abbattere, dunque, la cosiddetta \u201cquarta parete\u201d<\/strong>. \u201cAbbiamo fatto un buon lavoro &#8211; afferma Antonello Palombi &#8211; con i colleghi e conto di poter mostrare\u00a0una \u201cTosca\u201d assolutamente aderente allo spartito e alla scrittura del\u00a0compositore e che in un certo qual modo soddisfer\u00e0 il palato dei\u00a0tradizionalisti, ma mostrer\u00e0 anche le sue vere fattezze utilizzando la\u00a0tecnologia di cui disponiamo oggi.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Il video mapping \u2013 aggiunge\u00a0&#8211; servir\u00e0 solo ad arricchire e a dare una <strong>profondit\u00e0<\/strong>\u00a0che altrimenti sarebbe impossibile avere, creando nello spettatore la\u00a0sensazione di trovarsi in un altro luogo, non in teatro. Per il resto,\u00a0sia le scene che i costumi saranno assolutamente quelli del tempo.\u00a0Cronologicamente la nostra \u201cTosca\u201d \u00e8 inserita nel contesto storico nel\u00a0quale l\u2019autore l\u2019ha concepita.\u00a0Antonello Palombi ha vestito, da cantante, numerose volte il ruolo di\u00a0<strong>Mario Cavaradossi in \u201cTosca\u201d<\/strong>. Ora, per\u00f2, \u00e8 passato dall\u2019altro lato della\u00a0barricata, partecipando all\u2019allestimento da una prospettiva diversa.\u00a0\u201cE\u2019 stato un po\u2019- spiega il tenore e regista umbro &#8211; come costruire i\u00a0personaggi insieme con gli altri, cercando di ripulirli di alcuni vezzi,\u00a0abitudini, atteggiamenti posturali o di azione, o gestualit\u00e0 che dir si\u00a0voglia, cercando di svecchiarli il pi\u00f9 possibile. E\u2019 giusto che l\u2019opera si evolva, che gli attori\u00a0si evolvano, perch\u00e9 \u00e8 cambiato il mondo e le stesse persone sono\u00a0cambiate.\u00a0Noi siamo parte dell\u2019<strong>Orchestra (diretta da Luca\u00a0Ferrara)<\/strong>, nel senso che siamo \u201cstrumenti\u201d che funzionano a fiato con la\u00a0voce\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Chi ha dato un contributo non da poco all\u2019allestimento del \u201cRendano\u201d e\u00a0allo stesso regista Antonello Palombi, \u00e8 stato <strong>Rocco Pugliese<\/strong> che della\u00a0\u201cTosca\u201d in scena stasera\u00a0e domenica 24 gennaio (in replica\u00a0pomeridiana, ore 17,30) firma la scene e i costumi. Una vecchia\u00a0conoscenza del \u201cRendano\u201d Rocco Pugliese,\u00a0sia come regista che come direttore di scena.\u00a0Di lui si ricordano le regie di un\u00a0\u201cBarbiere di Siviglia\u201d del 1989.\u00a0\u201cL\u2019attuale direttore artistico Lorenzo Parisi \u2013\u00a0racconta Rocco Pugliese &#8211; si \u00e8 ricordato del lavoro che ho fatto\u00a0e mi ha chiamato per occuparmi delle scene e dei\u00a0costumi di \u201cTosca\u201d. Erano anni che\u00a0volevo ritornare, ma non c\u2019era stata l\u2019opportunit\u00e0\u201d.\u00a0Sulla novit\u00e0\u00a0tecnologica di \u201cTosca\u201d spiega: &#8221;Ho unito le\u00a0due cose per allargare il racconto affinch\u00e9 non finisca nella scatola\u00a0magica del palcoscenico. Nel completo rispetto del libretto e della\u00a0musica, ho cercato, per\u00f2, di interpretare determinati sentimenti.\u00a0Quindi \u2013 dice ancora Pugliese &#8211; ci sono emozioni rappresentate da quadri\u00a0famosi che vengono proiettati creando un ambiente diverso, ma il\u00a0contesto generale rimane quello di<strong> una lettura classica con l\u2019aggiunta\u00a0di tecnologie<\/strong> per accompagnare al meglio il pubblico presente in questo\u00a0viaggio meraviglioso che \u00e8 Tosca&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019allestimento, concepito appositamente per la stagione lirico- sinfonica del Teatro Rendano, prevede videomapping e altre innovazioni che abbattono la \u201cquarta\u00a0parete\u201d.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":51688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-51687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51687"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51688"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}