{"id":51823,"date":"2016-01-25T19:40:15","date_gmt":"2016-01-25T18:40:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/comunali-a-cosenza-paolini-scuote-il-pd-mi-candido-alle-primarie\/"},"modified":"2023-01-17T11:27:45","modified_gmt":"2023-01-17T10:27:45","slug":"71244-comunali-a-cosenza-paolini-scuote-il-pd-mi-candido-alle-primarie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/71244-comunali-a-cosenza-paolini-scuote-il-pd-mi-candido-alle-primarie\/","title":{"rendered":"Comunali a Cosenza, Paolini scuote il Pd: \u201cMi candido alle primarie\u201d (AUDIO INTERVISTA)"},"content":{"rendered":"<h4><strong>Il leader del Pse: \u201cCi\u00f2 permetter\u00e0 l\u2019insediamento della commissione dei garanti e l\u2019esecuzione, nei tempi e nei modi richiesti dal regolamento, di ogni altro adempimento necessario al regolare svolgimento delle primarie di coalizione\u201d.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">COSENZA \u2013 Enzo Paolini scuote\u00a0il Pd in vista delle prossime elezioni comunali a Cosenza e attraverso una lettera inviata ai segretari regionale e provinciale del partito, Ernesto Magorno e Luigi Guglielmelli, annuncia la propria intenzione a candidarsi alle primarie. <strong>\u201cIn conseguenza di quanto affermato dal segretario nazionale del Pd, Matteo Renzi, lo scorso 22 gennaio nel corso della Direzione nazionale del Partito democratico &#8211; scrive il leader del Pse &#8211; chiedo di dare corso con immediatezza alla predisposizione del regolamento per le primarie di coalizione per la scelta del candidato del centrosinistra a sindaco di Cosenza\u201d.<\/strong><\/p>\n<p>Proprio in virt\u00f9 di quanto asserito dal premier Renzi, Paolini, ha invitato il Pd a mettere in campo le Primarie alle quali, ha annunciato, sar\u00e0 candidato.<strong> L&#8217;avvocato Enzo Paolini,<\/strong> \u00e8 intervenuto in merito anche ai microfoni di <strong>Rlb Radioattiva<\/strong>.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><br \/>\n[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/01\/Paolini-Enzo-su-Primarie-centrosinistra.mp3&#8243;]<\/p>\n<p style=\"text-align: justify;\">\u201cQuesto &#8211; continua Paolini &#8211; in considerazione del fatto che intendo ufficialmente presentare la mia candidatura entro le ore 12 del 5 febbraio 2016, cio\u00e8 un mese prima della data fissata in tutta Italia per lo svolgimento delle elezioni primarie, nonch\u00e9 depositare la documentazione richiesta dallo statuto del Pd, condiviso da tutta la coalizione. Ci\u00f2 permetter\u00e0 l\u2019insediamento della commissione dei garanti e l\u2019esecuzione, nei tempi e nei modi richiesti dal regolamento, di ogni altro adempimento necessario al regolare svolgimento delle primarie di coalizione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il leader del Pse: \u201cCi\u00f2 permetter\u00e0 l\u2019insediamento della commissione dei garanti e l\u2019esecuzione, nei tempi e nei modi richiesti dal regolamento, di ogni altro adempimento necessario al regolare svolgimento delle primarie di coalizione\u201d.<\/p>\n","protected":false},"author":22,"featured_media":51824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-51823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51823"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51824"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}