{"id":51915,"date":"2016-01-27T17:10:12","date_gmt":"2016-01-27T16:10:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/discarica-donnici-ambientalisti-soddisfatti-ma-per-lassessore-bozzo-e-solo-paura\/"},"modified":"2023-01-17T11:27:56","modified_gmt":"2023-01-17T10:27:56","slug":"71723-discarica-donnici-ambientalisti-soddisfatti-ma-per-lassessore-bozzo-e-solo-paura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/71723-discarica-donnici-ambientalisti-soddisfatti-ma-per-lassessore-bozzo-e-solo-paura\/","title":{"rendered":"Discarica Donnici: ambientalisti soddisfatti, ma per l&#8217;assessore Bozzo era solo &#8216;paura&#8217;"},"content":{"rendered":"<h4 class=\"p1\" style=\"text-align: justify;\">Lavori\u00a0bloccati perch\u00e9 la ditta appaltatrice utilizz\u00f2 rifiuti per costruire la rampa d&#8217;accesso.<\/h4>\n<p class=\"p1\" style=\"text-align: justify;\"><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">DONNICI (CS) &#8211; Bocciato il progetto di realizzazione del centro di raccolta rifiuti di Donnici gli ambientalisti non esitano ad esprimere la propria soddisfazione. &#8220;Per la\u00a0decisione assunta dal Tar Calabria &#8211; scrive in una nota del Comitato di Difesa del Territorio di Donnici firmata da don Tommaso Scicchitano &#8211; sul sito che doveva sorgere in localit\u00e0 Albicello di Donnici esprimiamo gratitudine per il lavoro svolto e il risultato conseguito\u00a0dai tecnici ed avvocati di Donnici. <strong>Il Tar ha infatti recepito la principale delle censure mosse al progetto, e cio\u00e8 l&#8217;assenza di una preventiva valutazione di impatto ambientale, la cosiddetta Via.<\/strong> Il Tar, lo si ricorda, ha anche annullato il provvedimento \u201cspecie in considerazione della tipologia di attivit\u00e0 svolta in loco e del tipo di interessi di carattere ambientale coinvolti\u201d, come sostenuto dalla stessa autorit\u00e0 giudiziaria&#8221;. L&#8217;incubo di una nuova discarica sembra quindi essere scongiurato anche se a Palazzo dei Bruzi da mesi si sta lavorando per indire una nuova gara d&#8217;appalto. Non \u00e8 infatti da escludere che il Comune possa impugnare la sentenza.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">In una zona a vocazione agricola dove sorgono vitigni doc e dop il progetto dell&#8217;isola ecologica nato all&#8217;epoca di Perugini divent\u00f2 esecutivo con l&#8217;amministrazione Occhiuto. Grazie ad un finanziamento stanziato dalla Regione furono avviati i lavori poi bloccati dalla magistratura. Se non fossero state delle indagini, infatti, il centro di raccolta sarebbe attivo gi\u00e0 da un anno.\u00a0<strong>L&#8217;impresa che aveva vinto l&#8217;appalto, la Falbo Pietro di Luzzi, per costruire la rampa di ingresso all&#8217;isola ecologica aveva utilizzato dei rifiuti.<\/strong>\u00a0A certificarlo fu l&#8217;Arpacal dopo aver eseguito le analisi sui terreni che dopo aver classificato il materiale edile usato come rifiuti da trattare in appositi impianti aveva allertato sull&#8217;eccessiva presenza di zinco che aveva gi\u00e0 superato la soglia di contaminazione del suolo. Sospesi i lavori l&#8217;impresa \u00e8 stata denunciata, i rifiuti sono stati rimossi da Ecologia Oggi e il contratto \u00e8 stato risolto per inadempienze. Condannata la ditta ha risarcito il danno e il sito \u00e8 stato bonificato. La rampa \u00e8 stata ricostruita riutilizzando l&#8217;argilla degli scavi di piazza Bilotti, la strada consolidata e l&#8217;intero sito \u00e8 stato messo in sicurezza per evitare nuove frane.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L&#8217;assessore alla Salute Pubblica e Controllo Inquinamento Atmosferico del Comune di Cosenza,\u00a0Massimo Bozzo, in merito alla discarica di Donnici circa due mesi fa aveva affermato che &#8220;come avevo gi\u00e0 detto nel 2009\u00a0quando Perugini chiese un finanziamento alla Regione per la realizzazione del centro di raccolta che si trattava di un&#8217;ottima idea. Lo riconfermo oggi e lo riconfermer\u00f2 domani in quanto le isole ecologiche sono indispensabili per una buona raccolta differenziata. A Donnici \u00e8 successo che c&#8217;\u00e8 stata una comunicazione poco efficace con <strong>i cittadini reduci da anni in cui hanno convissuto con la discarica di Sant&#8217;Ippolito che non \u00e8 ancora stata bonificata e che non pu\u00f2 essere bonificata per tanti motivi.<\/strong> Non \u00e8 tra le discariche pi\u00f9 pericolose della nostra regione, ci sono solo rifiuti solidi urbani, oggi abbiamo altre priorit\u00e0. S\u00ec \u00e8 sul letto di un fiume, ma non rientra tra i siti da bonificare con urgenza. Sulla paura di Sant&#8217;Ippolito \u00e8 subentrata una strumentalizzazione politica e delle indagini della magistratura. Sar\u00e0 la storia a stabilire chi ha ragione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">E la storia, o meglio il TAR, finora ha dato ragione agli ambientalisti. &#8220;Purtroppo i progetti sono una questione politica &#8211; aveva affermato Arcangelo del Comitato di Difesa del Territorio di Donnici &#8211; questa vicenda lo ha dimostrato. <strong>Ci sono interessi\u00a0che vanno oltre la Valutazione di Impatto Ambientale e la conseguenze sulla salute pubblica.<\/strong> L\u00ec c&#8217;\u00e8 un fiume che passerebbe dall&#8217;interno della discarica. Fino ad oggi si sono bypassati diversi aspetti burocratici pur di avviare il progetto. Il che secondo noi fa pensare che ci sono degli interessi economici dietro per fare la discarica proprio in quel sito. Un sindaco prima di fare un lavoro del genere, che non \u00e8 una giostra per bambini, in un territorio ad alta vocazione agricola dovrebbe confrontarsi con la cittadinanza. Ci\u00f2 non \u00e8 avvenuto, noi ci siamo ritrovati all&#8217;improvviso le ruspe che scavavano senza sapere nulla&#8221;. Intanto per il progetto del Centro Raccolta Rifiuti, circa un anno, fa il Comune di Cosenza ha raddoppiato gli stanziamenti da 135mila euro a 270mila euro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lavori\u00a0bloccati perch\u00e9 la ditta appaltatrice utilizz\u00f2 rifiuti per costruire la rampa d&#8217;accesso.<\/p>\n","protected":false},"author":18,"featured_media":51916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-51915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51915"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51916"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}