{"id":51948,"date":"2016-01-28T11:36:18","date_gmt":"2016-01-28T10:36:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/kiave-torna-a-cosenza-e-presenta-stereotelling-un-album-piu-maturo-audio-intervista\/"},"modified":"2023-01-17T11:28:01","modified_gmt":"2023-01-17T10:28:01","slug":"71972-kiave-torna-a-cosenza-e-presenta-stereotelling-un-album-piu-maturo-audio-intervista","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/71972-kiave-torna-a-cosenza-e-presenta-stereotelling-un-album-piu-maturo-audio-intervista\/","title":{"rendered":"Kiave torna a Cosenza e presenta &#8216;StereoTelling&#8217;: &#8220;un album pi\u00f9 maturo&#8221; (AUDIO INTERVISTA)"},"content":{"rendered":"<h4>E&#8217; tornato nella sua citt\u00e0, Cosenza, per presentare il suo nuovo lavoro discografico, un album pi\u00f9 maturo e dal sound ricercato.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Mirko Filice, in arte Kiave, ha presentato ieri pomeriggio &#8220;<strong>StereoTelling<\/strong>&#8221; il nuovo album uscito ufficialmente lo scorso venerd\u00ec 22 gennaio. In tanti hanno preso parte all&#8217;evento alla Feltrinelli di Cosenza a Corso Mazzini, per incontrare Kiave, rapper cosentino apprezzatissimo nel panorama nazionale, capace di far convivere testi profondi con il pi\u00f9 puro intrattenimento, partito come indiscusso campione di freestyle \u00e8 diventato con gli anni un abile liricista e fine compositore della forma canzone pi\u00f9 classica.<\/p>\n<p><strong>Kiave<\/strong>, \u00e8 intervenuto questa mattina ai microfoni di<strong> Rlb Radioattiva<\/strong>, per parlare del suo album e dei suoi <strong>progetti da &#8220;StereoTelling&#8221; in poi&#8230;<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><br \/>\n[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/01\/Intervista-Kiave-Stereo-Telling.mp3&#8243;]<\/p>\n<p>StereoTelling \u00e8 un disco dal sound ricercato e spiccatamente funk che segna una profonda evoluzione musicale nella carriera di Kiave, un concept album incentrato sulla tecnica dello storytelling, in cui le rime di ogni traccia diventano un excursus narrativo che fotografa piccole storie di gente comune intenta a costruirsi il proprio futuro, racconti a volte seri e in altri casi pi\u00f9 sarcastici ma sempre carichi di uno slancio ricco di fiducia e di una sana autoironia. I temi forti sono quelli legati allo stato della societ\u00e0 attuale, alle difficolt\u00e0 di una vita precaria, alla continua ricerca del cambiamento oltre che quelli legati all&#8217;amore. Kiave\u00a0ha composto alcuni brani dopo i laboratori di scrittura creativa che ha tenuto con i giovani detenuti del carcere di Monza, un&#8217;esperienza forte grazie alla quale il rapper cosentino ha riflettuto su come la rabbia possa essere usata non solo come sterile sfogo, ma veicolata alla ricerca di un messaggio positivo.<\/p>\n<p>Gli ospiti al microfono sono<strong> Killacat, Johnny Marsiglia, Hyst, Patrick Benifei<\/strong> (Casino Royale\/Bluebeaters) e<strong> la nuova voce femminile in casa Macro Beats CRLN<\/strong>. Tra i produttori spiccano invece i nomi del producer francese <strong>Astronote<\/strong> (gi\u00e0 collaboratore di Kendrick Lamar), del canadese <strong>Marco Polo<\/strong> (di nuovo al lavoro in Italia dopo il fortunato EP &#8220;Per la mia gente&#8221; di Ghemon e Bassi Maestro) e nomi di primo piano della scena italiana come <strong>Big Joe, Macro Marco, Fid Mella, Iamseife, Cope e Gheesa<\/strong> che ha curato la maggior parte delle strumentali e che accompagner\u00e0 Kiave durante il tour. I beat sono stati arricchiti da numerosi strumenti suonati e i fiati nelle canzoni sono stati arrangiati dal <strong>sassofonista<\/strong> di<strong> Brunori Sas Mirko Onofrio<\/strong>. &#8220;StereoTelling&#8221; \u00e8 un lavoro solido, ispirato e ricco di sfumature che posiziona Kiave in quella cerchia ristretta di rapper italiani capace anche di parlare ad un pubblico pi\u00f9 attento e adulto.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Guarda il video del singolo LASCIAMI SBAGLIARE<\/span><\/strong><br \/>\n[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=HO9tv5aCl_U&#8221; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; tornato nella sua citt\u00e0, Cosenza, per presentare il suo nuovo lavoro discografico, un album pi\u00f9 maturo e dal sound ricercato.<\/p>\n","protected":false},"author":19,"featured_media":51949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-51948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51948"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51949"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}