{"id":51956,"date":"2016-01-28T13:05:17","date_gmt":"2016-01-28T12:05:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/giac\/"},"modified":"2023-08-13T09:27:43","modified_gmt":"2023-08-13T07:27:43","slug":"71993-giac","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/71993-giac\/","title":{"rendered":"Nelle foto di Guido Guglielmelli il ricordo di Cosenza a &#8220;cintuzzu&#8221; icona di un tempo che scorre inesorabile"},"content":{"rendered":"<h4>Il signor Giacinto, conosciuto da tutti come &#8220;Cintuzzu&#8221; &#8220;Sant&#8217;Antonio i l&#8217;uartu&#8221; era\u00a0una delle tante icone della citt\u00e0 che nel tempo sta perdendo i suoi personaggi. Discreto e silenzioso, si \u00e8 spento stamattina a 94 anni. In due scatti di Guido Guglielmelli il nostro ricordo\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Ogni citt\u00e0, grande o piccola che sia, ha le sue icone. Personaggi, a volta anche stravaganti in cui gli stessi cittadini molto spesso si immedesimano. La maggior parte di loro sono persone semplici, umili&#8230;. alcuni anche buffi nel modo di porsi e di parlare, ma con la loro personalit\u00e0 segnano il passare del tempo, incarnando lo spirito di appartenenza alla propria citt\u00e0 e che ti fanno dire quando parli con un amico<em> &#8220;ma come&#8230;. lo conoscono tutti&#8221;<\/em>. A Cosenza di queste figure ne sono passate tantissime, a volte silenziose, a volte rumorose ma sempre presenti. Bastava farsi un giro nel centro citt\u00e0 per incontrale, magari sempre negli stessi posti e loro sapevano strapparti una risata o un semplice sorriso con i loro gesti, uno sguardo e quel modo di fare unico. Hanno sempre cercato di svilupparsi in nicchie diverse poich\u00e9 funziona bene per il potere del cervello. Ora sempre pi\u00f9 persone sono interessate all&#8217;industria dei giochi. Tutte le informazioni necessarie sia per un principiante che per un professionista possono essere trovate sul sito <a href=\"https:\/\/gamblinganswer.com\/\" rel=\"noopener\">https:\/\/gamblinganswer.com\/<\/a><\/p>\n<p><span style=\"line-height: 1.5;\">Lo scorrere inesorabile degli anni\u00a0ci ha lasciato solo il ricordo di queste &#8220;stravaganti&#8221; figure.\u00a0Nei pi\u00f9 giovani \u00e8 stato tramandato dai padri e dai nonni. Come non ricordare le follie di &#8220;<\/span><strong style=\"line-height: 1.5;\">Totonno u squalu<\/strong><span style=\"line-height: 1.5;\">&#8221; oppure per chi era solito prendere il bus il saluto militare del &#8220;<\/span><strong style=\"line-height: 1.5;\">generale&#8221;<\/strong><span style=\"line-height: 1.5;\">, o\u00a0ancora\u00a0la simpatia di &#8220;<\/span><strong style=\"line-height: 1.5;\">maruzzu nan\u00e0<\/strong><span style=\"line-height: 1.5;\">&#8220;, quella du &#8220;<\/span><strong style=\"line-height: 1.5;\">cartunaru<\/strong><span style=\"line-height: 1.5;\">&#8221; oppure &#8220;<\/span><strong style=\"line-height: 1.5;\">u presidente<\/strong><span style=\"line-height: 1.5;\">&#8221; che in Via\u00a0dei mille bloccava sempre il traffico. I pi\u00f9 grandi ricorderanno\u00a0&#8220;<\/span><strong style=\"line-height: 1.5;\">a gazzellina<\/strong><span style=\"line-height: 1.5;\">&#8221; che a bordo della sua vespa in\u00a0Via Montesanto strillava per\u00a0vendere qualche giornale&#8230; A\u00a0proposito di giornali: ai pi\u00f9 anziani torner\u00e0 in mente un altro storico venditore <\/span><strong style=\"line-height: 1.5;\">&#8220;Nannuzzu&#8221;<\/strong><span style=\"line-height: 1.5;\">. Ed ancora<\/span><strong style=\"line-height: 1.5;\"> &#8220;Geppino Tri Mazzi&#8221; <\/strong><span style=\"line-height: 1.5;\">tifosissimo dei lupi,<\/span><strong><span style=\"line-height: 1.5;\"> &#8220;Pistiddra&#8221;<\/span><\/strong><span style=\"line-height: 1.5;\"> che\u00a0<\/span>andava<span style=\"line-height: 1.5;\">\u00a0su tutte le furie se battevi le mani<\/span><span style=\"line-height: 1.5;\">, &#8220;<\/span><strong style=\"line-height: 1.5;\">Mastro Ernesto<\/strong><span style=\"line-height: 1.5;\">&#8221; il muratore ubriaco che girava sempre su Corso Mazzini, &#8220;<\/span><strong style=\"line-height: 1.5;\">A lastica a 50 lire<\/strong><span style=\"line-height: 1.5;\">&#8221; ovvero il venditore pi\u00f9 famoso del ponte Mario Martire, &#8220;<\/span><strong style=\"line-height: 1.5;\">Ciccio Scuppetta<\/strong><span style=\"line-height: 1.5;\">&#8221; macchiettista nelle feste ma che di professione\u00a0faceva\u00a0il\u00a0falegname, il mitico &#8220;<\/span><strong style=\"line-height: 1.5;\">Mastri Peppe<\/strong><span style=\"line-height: 1.5;\">&#8221; custode dello stadio Morrone che quando si creava troppa calca scopa alla\u00a0mano, usciva a mettere ordine, &#8220;<\/span><strong style=\"line-height: 1.5;\">Micarano<\/strong><span style=\"line-height: 1.5;\">&#8221; famoso banditore che girava per le strade ad\u00a0annunciare con la tromba vendite e offerte alimentari in quella Cosenza vecchia cuore pulsante della citt\u00e0 negli anni 40 e 50. Ed ancora &#8220;<strong>Gigino Chiuritu<\/strong>&#8220;,&#8221;<\/span><strong style=\"line-height: 1.5;\">Ciccio Fred Scotti<\/strong><span style=\"line-height: 1.5;\">&#8221; che dava da mangiare ad un leone e faceva il cantante della malavita cosentina, le caramelle sognate dai bambini ma solo se erano di\u00a0&#8220;<\/span><strong style=\"line-height: 1.5;\">Ciccillo u caramellaru<\/strong><span style=\"line-height: 1.5;\">&#8220;&#8230;. \u00a0fino alla pi\u00f9 recente scomparsa del grande &#8220;<\/span><strong style=\"line-height: 1.5;\">Totonno Chiappetta<\/strong><span style=\"line-height: 1.5;\">&#8220;. Persone dicevamo, figure che il tempo ha trasformato in miti e ricordi di una Cosenza\u00a0che non c&#8217;\u00e8 pi\u00f9.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-71999\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/01\/Signor-Giacinto11.jpg\" alt=\"Signor Giacinto1\" width=\"735\" height=\"490\" title=\"\"><\/p>\n<p>Oggi un&#8217;altra icona della nostra citt\u00e0 ci ha salutato. Non vedremo pi\u00f9 su Corso Mazzini il volto notissimo del <strong>signor Giacinto Tarantino<\/strong>, conosciuto da tutti come &#8220;<strong>Cintuzzu Sant&#8217;Antonio i l&#8217;uartu<\/strong>&#8220;. Devoto al santo, era solito chiedere le offerte. Lo trovavi ogni giorno su Corso Mazzini, all&#8217;altezza di &#8220;Piazza XI Settembre&#8221;. Con la sua reliquia stretta tra le mani sorridendo ti chiedeva: &#8220;<em>perfav\u00f2 mi\u00a0ci mindi cinquanta lire pi\u00a0Sant&#8217;Antonio?&#8221;<\/em>. Grazie a\u00a0questi due splendidi scatti del fotografo <strong>Guido Guglielmelli<\/strong>, vogliamo ricordare anche noi, con simpatia e un pizzico di nostalgia, il signor Giacinto e tutti i personaggi di Cosenza che non ci sono pi\u00f9.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-72000\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/01\/Signor-giacinto2.jpg\" alt=\"Signor giacinto2\" width=\"606\" height=\"908\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il signor Giacinto, conosciuto da tutti come &#8220;Cintuzzu&#8221; &#8220;Sant&#8217;Antonio i l&#8217;uartu&#8221; era\u00a0una delle tante icone della citt\u00e0 che nel tempo sta perdendo i suoi personaggi. Discreto e silenzioso, si \u00e8 spento stamattina a 94 anni. In due scatti di Guido Guglielmelli il nostro ricordo\u00a0<\/p>\n","protected":false},"author":22,"featured_media":51957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-51956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=51956"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/51956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/51957"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=51956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=51956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=51956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}