{"id":52410,"date":"2016-02-05T15:30:38","date_gmt":"2016-02-05T14:30:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tutto-pronto-per-la-seconda-edizione-del-carnevale-di-rende-musica-danza-e-sfilate\/"},"modified":"2023-01-17T11:29:03","modified_gmt":"2023-01-17T10:29:03","slug":"73619-tutto-pronto-per-la-seconda-edizione-del-carnevale-di-rende-musica-danza-e-sfilate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/73619-tutto-pronto-per-la-seconda-edizione-del-carnevale-di-rende-musica-danza-e-sfilate\/","title":{"rendered":"Tutto pronto per la seconda edizione del Carnevale di Rende: musica, danza e sfilate"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><strong>Saranno tantissime le sorprese, frutto di un intenso lavoro e tanta creativit\u00e0.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE (CS) &#8211; Afredo Bruno e Giuseppe Garofalo coordineranno tutto in una tre giorni di felicit\u00e0 e allegria. Un Carnevale che, come lo scorso anno, si svolger\u00e0 in via Rossini. Il<strong> 7, 8, 9 febbraio<\/strong> le famiglie di Rende e dell\u2019area urbana scenderanno in strada per prendere parte ad un ricco cartellone di eventi con attrattive mirate soprattutto alla gioia dei bambini. La grande festa partir\u00e0 alle 15.00 di un 7 febbraio scoppiettante, con gli Sbandieratori di Bisignano, le majorettes delle scuole di Cosenza e Parenti, gli abiti d\u2019epoca con undici dame dell\u2019800 di Emilia Iuele e abiti d\u2019epoca realizzati anche dall\u2019Istituto L. Da Vinci, i tamburi della Sila, le scuole di ballo della Azzurra Ballet School di Azzurra Gardi, la New Ballet School, la New Generetion Ballet Arabesque, la Step Dance, University Of Dance, i trampolieri, <strong>pagliacci e Mangiafuoco<\/strong> per la sfilata tutta musica e gran chiasso festoso. Nel cuore della grande sfilata non mancheranno le mascotte di Disney con \u201cFun Universe\u201d e \u201c Brighella animazioni\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201cI Pagliassi\u201d con i loro giochi di prestigio presentano in anteprima lo spettacolo \u201cLight Toys\u201d. Ed ancora sempre nella sfilata inaugurale del 7 febbraio protagonisti saranno anche le accattivanti <strong>coreografie delle \u201c Danzatrici di Iside\u201d<\/strong>. Anche per questa edizione ha garantito la sua presenza e il suo contributo artistico il regista e l\u2019attore teatrale cosentino William Gatto. E suo sar\u00e0 il lavoro che andr\u00e0 in scena sempre nella giornata del 7 febbraio: Giangurgolo, Pascariaddru ed i frizzi e lazzi amorosi dell\u2019allegra carovana della commedia dell\u2019arte. Protagonista sar\u00e0 la musica con il gruppo cosentino dei <strong>Swing Fratis<\/strong> guidato da Massimo Gazzaruso che con il loro brio animeranno una giornata indimenticabile. Altra location importante del \u201cIl Carnevale di Rende\u201d \u00e8 il <strong>palaghiaccio<\/strong> di via Rossini, dove si potr\u00e0 assistere a sfilate in maschera con i pattini. Tra i partecipanti da sottolineare la presenza del Vespa Club. I motori e i rumori del Carnevale 2016 si riscaldano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saranno tantissime le sorprese, frutto di un intenso lavoro e tanta creativit\u00e0.<\/p>\n","protected":false},"author":22,"featured_media":52411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-52410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52410"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52411"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}