{"id":52434,"date":"2016-02-05T18:42:25","date_gmt":"2016-02-05T17:42:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/roberto-occhiuto-contro-anas-nuova-figuraccia\/"},"modified":"2023-01-17T11:29:06","modified_gmt":"2023-01-17T10:29:06","slug":"73709-roberto-occhiuto-contro-anas-nuova-figuraccia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/73709-roberto-occhiuto-contro-anas-nuova-figuraccia\/","title":{"rendered":"Roberto Occhiuto contro Anas: \u201cNuova figuraccia\u201d"},"content":{"rendered":"<p><strong>Il deputato di Forza Italia critica il gestore della rete stradale ed autostradale italiana per quanto verificatosi ieri su alcuni tratti delle strade calabresi.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p>COSENZA \u2013 <strong>Anas<\/strong> ancora sotto attacco dopo le polemiche per il caos dello scorso 19 gennaio con il tratto cosentino dell\u2019<strong>A3<\/strong> invaso per ore dagli automobilisti <strong>bloccati dalla neve<\/strong>. <strong>Roberto Occhiuto<\/strong>, deputato e vice coordinatore calabrese di <strong>Forza Italia<\/strong>, critica il gestore della rete stradale ed autostradale italiana per quanto verificatosi ieri su alcuni tratti delle strade calabresi.<br \/>\n\u201cCome in un copione gi\u00e0 scritto \u2013 afferma il deputato cosentino &#8211; dopo il danno la beffa. Dopo le code per la nevicata dello scorso gennaio, con gli automobilisti intrappolati per ore sulla A3, l&#8217;Anas \u00e8 corsa ai ripari, ma la soluzione adottata ha creato ulteriori enormi disagi\u201d.<br \/>\n&nbsp;<\/p>\n<h2><strong>Occhiuto: \u201cL\u2019Anas ha avuto paura di fare un\u2019altra brutta figura\u201d<\/strong><\/h2>\n<p>&nbsp;<br \/>\n\u201cLa paura di fare una nuova brutta figura \u2013 prosegue Occhiuto &#8211; ha spinto ad effettuare dei controlli che viste le condizioni atmosferiche sono stati senza dubbio il frutto di un eccesso di zelo e per di pi\u00f9 hanno causato lunghe code, con conseguenti complicazioni alla circolazione stradale. Sia che l&#8217;obiettivo fosse mettersi al riparo dalle polemiche (e speriamo proprio di no) sia che fosse garantire la viabilit\u00e0 senza creare problemi agli utenti, l&#8217;Anas ha evidentemente fallito, dando una nuova prova di inettitudine per cui presenter\u00f2 un&#8217;interrogazione al <strong>Ministro delle Infrastrutture e dei Trasporti, Graziano Delrio<\/strong>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il deputato di Forza Italia critica il gestore della rete stradale ed autostradale italiana per quanto verificatosi ieri su alcuni tratti delle strade calabresi.<\/p>\n","protected":false},"author":22,"featured_media":52435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-52434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52434"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52435"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}