{"id":52456,"date":"2016-02-06T09:35:31","date_gmt":"2016-02-06T08:35:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/latista-antonio-oliva-torna-a-rende-con-una-mostra-di-pittura\/"},"modified":"2023-01-17T11:29:08","modified_gmt":"2023-01-17T10:29:08","slug":"73761-latista-antonio-oliva-torna-a-rende-con-una-mostra-di-pittura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/73761-latista-antonio-oliva-torna-a-rende-con-una-mostra-di-pittura\/","title":{"rendered":"L&#8217;artista Antonio Oliva torna a Rende con una mostra di pittura"},"content":{"rendered":"<h4><strong>Come sempre, l&#8217;artista trae ispirazione dal magico mondo di colori, pennelli, tavolozze, gessetti e cavalletti.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE (CS) &#8211; La nuova mostra si presenta come una vera e propria <strong>avventura cinetica e futurista<\/strong>, alla scoperta di un nuovo mondo rivoluzionario e liberatorio. Le opere, cariche di &#8221;espressionismo dinamico&#8221;\u00a0saranno esposte da domani al 21 febbraio, presso Artimede Belle Arti, in via della Resistenza 140, tutti i giorni dalle 9,30 alle 12,30 e dalle 16,30 alle 19,30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come sempre, l&#8217;artista trae ispirazione dal magico mondo di colori, pennelli, tavolozze, gessetti e cavalletti.<\/p>\n","protected":false},"author":22,"featured_media":52457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-52456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52456"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52457"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}