{"id":52611,"date":"2016-02-10T04:00:57","date_gmt":"2016-02-10T03:00:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/intimidazioni-ai-sindaci-calabria-in-testa\/"},"modified":"2023-01-17T11:29:28","modified_gmt":"2023-01-17T10:29:28","slug":"74542-intimidazioni-ai-sindaci-calabria-in-testa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/74542-intimidazioni-ai-sindaci-calabria-in-testa\/","title":{"rendered":"Intimidazioni ai sindaci, Calabria in testa"},"content":{"rendered":"<p><strong>E&#8217; il quadro che fornisce Avviso Pubblico, Enti locali e Regioni per la formazione civile contro le mafie. Dal primo gennaio boom di minacce in tutta Italia.<\/strong><!--more--><br \/>\n&nbsp;<br \/>\nROMA &#8211; Sono gi\u00e0 30, dall&#8217;inizio dell&#8217;anno, gli atti intimidatori e le minacce nei confronti degli <strong>amministratori locali<\/strong>, i <strong>sindaci<\/strong> innanzitutto: nel 37% dei casi le intimidazioni sono nei loro confronti, nel 16% verso gli assessori, nel 12,5% dei casi nei confronti sia di attivisti politici che di personale della pubblica amministrazione. E&#8217; il quadro, allarmato, che fornisce <strong>Avviso Pubblico, Enti locali e Regioni per la formazione civile contro le mafie<\/strong>. Nella met\u00e0 dei casi, \u00e8 l&#8217;incendio il mezzo principale di intimidazione, soprattutto nel <strong>Mezzogiorno<\/strong>; seguono, soprattutto al centro nord, le lettere anonime (39%) contenenti minacce e, nel 7% dei casi, aggressioni fisiche e verbali, avvenute nei confronti del sindaco di Civitavecchia, di Calcinato (Brescia) e di Erba (Como). Nel 70% dei casi sono state bruciate auto di propriet\u00e0 personali, nel 15% strutture comunali e per un altro 15% case di propriet\u00e0.<br \/>\n&nbsp;<br \/>\nIn <strong>Calabria<\/strong>, Puglia, Sardegna e Sicilia, sono stati colpiti, in modo diretto o indiretto, amministratori gi\u00e0 intimiditi nel passato. Nel dettaglio, i casi di minaccia sono stati registrati in <strong>9 regioni<\/strong>, 17 province e 25 comuni, il 70% al sud, il 27% al nord e il 3% al centro. <strong>I casi registrati in Calabria<\/strong> <strong>sono i pi\u00f9 numerosi<\/strong>, ben 9; segue la Sicilia, la Puglia e il Veneto con 5 casi di intimidazione ciascuno. Poi la Lombardia, dove si segnalano due casi, la Campania, il Lazio, la Sardegna e l&#8217;Emilia Romagna fanno registrare un caso ciascuno. &#8220;Siamo molto preoccupati e lo abbiamo denunciato in diverse sedi istituzionali e pubbliche &#8211; dichiara <strong>Roberto Mont\u00e0<\/strong>, presidente di Avviso Pubblico -. Chiediamo al Governo di mettere in atto tutte le misure di sicurezza possibili e al Parlamento di esaminare e approvare rapidamente le proposte di legge avanzate dalla commissione parlamentare d&#8217;inchiesta presieduta dalla senatrice <strong>Doris Lo Moro<\/strong>. Non \u00e8 pi\u00f9 accettabile questa serie di attacchi sempre pi\u00f9 frequenti e pericolosi nei confronti degli agli amministratori locali e non \u00e8 pi\u00f9 tollerabile l&#8217;impunit\u00e0 di chi compie questi gesti&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; il quadro che fornisce Avviso Pubblico, Enti locali e Regioni per la formazione civile contro le mafie. Dal primo gennaio boom di minacce in tutta Italia.<\/p>\n","protected":false},"author":22,"featured_media":52612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-52611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52611"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52612"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}