{"id":52700,"date":"2016-02-11T12:23:13","date_gmt":"2016-02-11T11:23:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/74883\/"},"modified":"2023-01-17T11:29:39","modified_gmt":"2023-01-17T10:29:39","slug":"74883-74883","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/74883-74883\/","title":{"rendered":"Gian Antonio Stella sul Corriere prende di mira Giacomo Mancini junior"},"content":{"rendered":"<p class=\"p1\"><strong>Nella sua rubrica &#8220;Tuttifrutti&#8221; sul Corriere della Sera, il noto giornalista Gian Antonio Stella \u00e8 tornato ad occuparsi dei fatti di Calabria.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s1\">COSENZA &#8211; Questa volta <strong>Gian Antonio Stella<\/strong> ha puntato la sua attenzione su <strong>Giacomo Mancini junior<\/strong>, titolando il suo pezzo <strong>&#8220;Il rampollo volubile cambia sempre bandiera&#8221;<\/strong>. Il riferimento \u00e8 ovviamente rivolto all&#8217;ultimo <strong>cambio di casacca<\/strong> del nipote dell&#8217;illustre sindaco di Cosenza, passato in pochissimi anni dal centrosinistra a <strong>Forza Italia<\/strong> per far attracco oggi &#8211; scrive Stella &#8211; verso nuovi lidi pi\u00f9 vicini al <strong>Pd<\/strong>. &#8220;<\/span>In questi giorni &#8211; riporta il giornalista veneto sull&#8217;edizione cartacea di mercoled\u00ec del <strong>Corriere della Sera<\/strong> &#8211; segnati dall\u2019ennesimo attacco (&#8216;ha perso la testa&#8217;) al sindaco di Cosenza <strong>Mario Occhiuto<\/strong>, buttato gi\u00f9 da una parte della stessa destra che l\u2019aveva eletto, viene dato dalle parti di Denis Verdini sotto la cui Ala, dicono, sogna di correre alla conquista del Comune con l\u2019appoggio del Pd. Il tutto dopo aver circumnavigato un po\u2019 tutti i porti e i porticcioli partitici. Il vecchio Giacomo, com\u2019\u00e8 noto, era un socialista. Anzi &#8211; continua Stella &#8211; fu addirittura segretario del <strong>Psi<\/strong> nonch\u00e9, pi\u00f9 tardi, padre della svolta al Midas (lo chiamavano &#8216;<strong>Craxi Driver<\/strong>&#8216;) che port\u00f2 al potere Bettino. Lo stesso Junior cos\u00ec esord\u00ec a <strong>Montecitorio<\/strong>: <strong>socialista<\/strong>. Prima grazie all\u2019alleanza con la sinistra postcomunista poi con la <strong>Rosa nel Pugno<\/strong>. Con cui alle \u00abcomunali\u00bb del maggio 2006 sfid\u00f2 da sinistra i <strong>Ds, la Margherita e i dipietristi<\/strong> contando sui voti dei rifondaroli comunisti. Piantati in asso insieme con tutta la sinistra nel 2009 quando, senza prebende per la caduta di <strong>Prodi<\/strong> e della legislatura in cui era deputato radical-socialista, si candid\u00f2 alle Europee con Forza Italia. Per essere poi \u00abrecuperato\u00bb l\u2019anno dopo la bocciatura dal post-missino <strong>Giuseppe Scopelliti<\/strong> come assessore regionale della giunta calabrese di destra. Una conversione &#8211; scrive sempre il giornalista del Corriere &#8211; impreziosita dall\u2019omaggio alla tomba di <strong>Ciccio Franco<\/strong>, leader della rivolta calabrese del 1970 durante la quale era stato anche impiccato un manichino che rappresentava il vecchio Giacomo\u2026 Finita anche quell\u2019esperienza, Giacomino si era via via allontanato dalla destra fino ad uscire da Forza Italia per puntare la prua, visto il vento, verso il porto renziano. Indimenticabile il giudizio di \u00abJunior\u00bb su fedelissimi che non l\u2019avevano seguito nell\u2019addio al partito berlusconiano (\u00abvoltagabbana\u00bb) e pi\u00f9 ancora un tweet dove in dialetto invitava i cosentini a liberarsi della feccia (\u00abara cupa a famazza\u00bb) politica e una pagina <strong>Facebook<\/strong> in cui incitava a voltare pagina: \u00abA casa i faccendieri, i saltimbanchi, i collezionisti di incarichi e prebende\u2026\u00bb Un gigante&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella sua rubrica &#8220;Tuttifrutti&#8221; sul Corriere della Sera, il noto giornalista Gian Antonio Stella \u00e8 tornato ad occuparsi dei fatti di Calabria.<\/p>\n","protected":false},"author":22,"featured_media":52701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-52700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52700"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52701"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}