{"id":52764,"date":"2016-02-12T13:30:20","date_gmt":"2016-02-12T12:30:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/le-ragioni-di-sergio-nucci-il-male-va-riconosciuto-da-tutti\/"},"modified":"2023-01-17T11:29:51","modified_gmt":"2023-01-17T10:29:51","slug":"75089-le-ragioni-di-sergio-nucci-il-male-va-riconosciuto-da-tutti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/75089-le-ragioni-di-sergio-nucci-il-male-va-riconosciuto-da-tutti\/","title":{"rendered":"Le ragioni di Sergio Nucci: &#8220;Il male va riconosciuto&#8221;"},"content":{"rendered":"<p><strong>L&#8217;ex consigliere comunale elenca sul proprio blog i motivi che lo hanno portato a sfiduciare il primo cittadino di Cosenza, Mario Occhiuto.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; <strong>Sergio Nucci<\/strong>, uno dei <strong>17 consiglieri comunali<\/strong> che sabato scorso hanno fatto cadere il sindaco di Cosenza,<strong> Mario Occhiuto<\/strong>, sul suo blog <strong>Buongiorno Cosenza<\/strong> (<a href=\"https:\/\/quicosenza.it\/news\/356\">leggi qui<\/a>), rivela dettagliatamente le ragioni che lo hanno portato a tale decisione. &#8220;Per essere combattuto &#8211; scrive Nucci prendendo spunto dalla storia della <strong>Madonna del Pilerio<\/strong> &#8211; il male, va innanzitutto conosciuto e riconosciuto, da tutti&#8221;. L&#8217;ex consigliere comunale entra nello specifico, elencando, punto per punto, tutte le incongruenze dell&#8217;amministrazione Occhiuto. A partire dal &#8220;<strong>buco da 800mila euro all&#8217;azienda dei trasporti pubblici cittadini<\/strong>&#8220;, fino ad arrivare agi incarichi &#8220;non quantizzabili&#8221;. Nucci si chiede &#8220;<strong>come si aggiudicano gli appalti<\/strong>? Forse partecipando in solitaria come per i 22 milioni di euro di Piazza Bilotti? Chi e perch\u00e9 ha deciso che la Curia di Cosenza dovesse avere un business a sei zeri sui loculi del cimitero, mentre la parte comunale frana?&#8221;. E poi ancora &#8220;<strong>Quanti sono i debiti accumulati dal Comune?<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Mutui pluriennali accesi per finanziare le opere in cantiere &#8211; scrive sempre l&#8217;ex consigliere &#8211; ma nessuno, nemmeno i consiglieri comunali, conoscono il reale stato dei conti pubblici. Sappiamo che i revisori hanno mosso pesanti rilievi, ma in una situazione di ignoranza complice e diffusa ognuno pu\u00f2 dire ci\u00f2 che vuole, come per esempio che i conti siano in attivo&#8230; Cosenza \u00e8 stata a rischio dissesto economico, dopodich\u00e9 come molti Comuni si \u00e8 tentata la strada del pre-dissesto, <strong>150 milioni di euro prestati dalla Cassa Depositi e Prestiti e che i cosentini pagheranno per i prossimi trent\u2019anni<\/strong>. Ci sono stati i rilievi della Corte dei conti, poi magicamente rientrati ai primi aggiustamenti. Ma nessuno, ad oggi, conosce il debito del Comune di Cosenza. <strong>Due milioni e 700mila euro di debiti fuori bilancio vi dicono qualcosa<\/strong>? Un milione e 800mila dei quali derivanti da \u201caccensione prestiti\u201d. Sentenze esecutive per oltre 800mila euro eppure paghiamo per le cause del Comune fior di avvocati \u2026. O meglio fior di avvocato&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Nel suo messaggio ai cittadini Sergio Nucci critica anche il <strong>concetto di citt\u00e0<\/strong> voluto da Occhiuto in questi anni, con il <strong>Castello Svevo<\/strong> divenuto un simbolo della sua politica e &#8220;diventato &#8211; si legge ancora nella sua nota &#8211; poco pi\u00f9 che un <strong>lounge bar, un simbolo della movida, lambito da luci psichedeliche, le stesse che colorano la nostra citt\u00e0 rendendola simile a una Las Vegas di provincia<\/strong>. La comunicazione, grande fiore all&#8217;occhiello di questa amministrazione uscente, ha preso lo scivolone dell&#8217;architetto della Soluzione finale. Ricordate <strong>Himmler<\/strong>? Ebbene non credo sia stato solo una svista, ma un concetto pi\u00f9 profondo: la storia non si pu\u00f2 cancellare, ci hanno risposto. Ma \u00e8 con questa storia che vogliamo promuovere Cosenza? Con la ricerca di un tesoro che non c&#8217;\u00e8? Con la dichiarata pura illusione di cercare per il gusto di cercare. Le feste, le sagre, il popolo che deve dimenticare, distrarsi. Sono questi i concetti tipici della destra, che si \u00e8 incarnata perfettamente nello spirito di questa amministrazione che abbandona il Palazzo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Non manca una critica all&#8217;informazione, controllata &#8211; secondo il consigliere &#8211; minuziosamente dall&#8217;architetto. &#8220;<strong>Le voci critiche spente, perseguitate, messe alla berlina<\/strong>. I siti di informazione chiusi, i giornali amici, le persone scomode fatte fuori. L&#8217;attivit\u00e0 dei consiglieri completamente annullata dalla non risposta, dalle carte nascoste, dalle delegittimazioni personali, odiose e vigliacche. Una arroganza supportata da opportune protezioni, quelle che forse oggi sono saltate. Una scorta personale che costituisce un costo per i cittadini&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Nucci chiude il suo scritto cos\u00ec: &#8220;<strong>Cos&#8217;altro avremmo dovuto fare, lasciare che ogni giorno la coscienza dei cosentini venisse drogata da luci e lucine?<\/strong> Vi siete mai chiesti da dove vengono quelle luci? Vi siete mai chiesti chi hanno messo nella stanza dei bottoni per accendere questo immenso lunapark che \u00e8 diventato la nostra citt\u00e0? E noi, noi cosentini, cosa stiamo arrivando a pensare: che &#8220;almeno questo qualcosa la fa&#8221;? E dunque che sia lecito fare in qualsiasi modo, basta che qualcosa venga fatta. Sono anni che il radicamento mafioso nei territori si sostanzia con la criminalit\u00e0 che si sostituisce allo Stato. Lo Stato non da sicurezza, non da lavoro. E cos\u00ec le popolazioni si rivolgono ai padrini. Almeno loro qualcosa fanno. E&#8217; davvero cos\u00ec che ragiona la <strong>citt\u00e0 di Telesio<\/strong>? Se \u00e8 questo che pensiamo non basteranno diciassette consiglieri, una consiliatura finita, un commissario prefettizio, una indagine della magistratura.\u00a0 <strong>Rivolgiamoci alla Vergine<\/strong>, guardiamo il suo volto: \u00e8 il simbolo della citt\u00e0. Se qualcuno deve prendere su di s\u00e9 la peste, \u00e8 necessario che ci sia per\u00f2 qualcun altro che la denunci, che la faccia vedere, che la renda riconoscibile. Questo \u00e8 stato il nostro ruolo. Non pretendiamo che qualcuno ce lo riconosca. Ma siamo sicuri che i cittadini di Cosenza, svegliatisi dall&#8217;incantesimo, sapranno alla fine da che parte stare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ex consigliere comunale elenca sul proprio blog i motivi che lo hanno portato a sfiduciare il primo cittadino di Cosenza, Mario Occhiuto.<\/p>\n","protected":false},"author":22,"featured_media":52765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-52764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52764"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52765"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}