{"id":52839,"date":"2016-02-13T18:02:32","date_gmt":"2016-02-13T17:02:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scotto-al-pd-a-cosenza-no-ad-alleanze-con-morrone-e-i-gentile\/"},"modified":"2023-01-17T11:30:02","modified_gmt":"2023-01-17T10:30:02","slug":"75327-scotto-al-pd-a-cosenza-no-ad-alleanze-con-morrone-e-i-gentile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/75327-scotto-al-pd-a-cosenza-no-ad-alleanze-con-morrone-e-i-gentile\/","title":{"rendered":"Scotto al Pd: \u201cA Cosenza no ad alleanze con Morrone e i Gentile\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>L\u2019ultimatum del capogruppo di Sinistra Italiana alla Camera dei Deputati: \u201cMi pare si stiano gettando le premesse per un&#8217;insalata russa.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\nLAMEZIA TERME (CZ) &#8211; &#8220;La caduta di <strong>Occhiuto<\/strong> \u00e8 un fatto da benedire. Si chiude un&#8217;esperienza di governo regressiva, in una citt\u00e0 strategica per lo sviluppo di questa regione&#8221;. Lo ha detto il <strong>capogruppo di Sinistra Italiana<\/strong> alla <strong>Camera dei Deputati Arturo Scotto<\/strong> intervenendo in conferenza stampa a Lamezia Terme. &#8220;Il problema &#8211; ha aggiunto &#8211; \u00e8 che alla caduta di una coalizione di centrodestra, non si sta creando un&#8217;alternativa di centrosinistra. Mi pare si stiano gettando le premesse per un&#8217;insalata russa che vede insieme i <strong>Gentile<\/strong>, come una sorta di obolo da pagare alla nuova compagine governativa, e addirittura una parte di <strong>Forza Italia<\/strong> con <strong>Ennio Morrone<\/strong>. Come si fa a costruire un&#8217;alleanza con chi, come Morrone, ha interessi nella sanit\u00e0 privata in una regione dove la sanit\u00e0 \u00e8 commissariata e per avere una tac occorrono tempi biblici? Se si vuole creare a Cosenza una proposta di governo veramente di discontinuit\u00e0, noi siamo pronti a dialogare: non siamo n\u00e9 chiusi n\u00e9 settari&#8221;. &#8220;Se si vuole creare &#8211; ha concluso Scotto &#8211; un&#8217;alleanza del <strong>Pd<\/strong> con i Gentile ed Ennio Morrone, saremo i promotori della costruzione di un centrosinistra alternativo per la citt\u00e0 di Cosenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ultimatum del capogruppo di Sinistra Italiana alla Camera dei Deputati: \u201cMi pare si stiano gettando le premesse per un&#8217;insalata russa.<\/p>\n","protected":false},"author":22,"featured_media":52840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-52839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52839"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52840"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}