{"id":52888,"date":"2016-02-15T12:52:00","date_gmt":"2016-02-15T11:52:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/chiesto-lergastolo-per-il-boss-cosentino-franco-presta\/"},"modified":"2023-01-17T11:30:08","modified_gmt":"2023-01-17T10:30:08","slug":"75741-chiesto-lergastolo-per-il-boss-cosentino-franco-presta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/75741-chiesto-lergastolo-per-il-boss-cosentino-franco-presta\/","title":{"rendered":"&#8220;Terminator IV&#8221;, chiesto l&#8217;ergastolo per il boss cosentino Franco Presta"},"content":{"rendered":"<p><strong>Il pubblico ministero della Dda di Catanzaro, Pierpaolo Bruni, ha chiesto la condanna all&#8217;ergastolo per il presunto boss della &#8216;ndrangheta cosentina Franco Presta.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>COSENZA &#8211; La richiesta \u00e8 stata avanzata ai giudici della Corte d&#8217;assise di Cosenza nel corso della requisitoria nel processo &#8220;<strong>Terminator IV<\/strong>&#8221; sulla guerra tra cosche negli anni novanta nel cosentino. Il Pm ha chiesto anche la condanna a nove anni e sei mesi per i collaboratori di giustizia <strong>Vincenzo Dedato<\/strong> e <strong>Francesco Amodio<\/strong>, imputati nel processo con Franco Presta. Nel corso della requisitoria il pubblico ministero ha ripercorso lo scontro tra le cosche della &#8216;ndrangheta cosentina avvenuto negli anni novanta. L&#8217;accusa ha ricostruito anche gli <strong>omicidi<\/strong> di<strong> Antonio Sena, Antonio Sassone, Vittorio Marchio ed Enzo Pelazza<\/strong>. Al termine della requisitoria il processo \u00e8 stato rinviato a gioved\u00ec per le arringhe difensive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il pubblico ministero della Dda di Catanzaro, Pierpaolo Bruni, ha chiesto la condanna all&#8217;ergastolo per il presunto boss della &#8216;ndrangheta cosentina Franco Presta.<\/p>\n","protected":false},"author":22,"featured_media":52889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-52888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52888"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52889"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}