{"id":52971,"date":"2016-02-17T10:27:49","date_gmt":"2016-02-17T09:27:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/referendum-sulle-trivellazioni-mare-si-vota-17-aprile\/"},"modified":"2023-01-17T11:30:22","modified_gmt":"2023-01-17T10:30:22","slug":"76016-referendum-sulle-trivellazioni-mare-si-vota-17-aprile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/76016-referendum-sulle-trivellazioni-mare-si-vota-17-aprile\/","title":{"rendered":"Referendum sulle trivellazioni in mare, si vota il 17 Aprile"},"content":{"rendered":"<p><strong>Renzi tenta di boicottare la consultazione popolare per favorire le multinazionali del petrolio. <\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">ROMA &#8211; Il capo dello Stato Sergio Mattarella ha firmato il decreto sulle norme in materia ambientale che indice il referendum popolare sulle trivelle per il prossimo 17 Aprile.\u00a0Il referendum contro le trivelle per la ricerca di petrolio in Adriatico non si far\u00e0 nello stesso giorno delle elezioni amministrative a Giugno, nonostante appelli e sollecitazioni a non sprecare centinaia di milioni di euro.\u00a0Greenpeace accoglie la notizia rimettendo ai veri responsabili di questa decisione, Renzi e i suoi ministri, responsabilit\u00e0 gravissime.\u00a0Secondo l&#8217;associazione ambientalista, lo spreco gratuito di risorse pubbliche coincide in questo caso con una sottrazione di democrazia ingiustificabile. La durata della campagna elettorale risulta compressa al limite della legge: \u00e8 possibile, ad esempio, che non vi siano i tempi tecnici per garantire almeno i 45 giorni previsti dalla legge sulla par condicio.\u00a0Secondo Greenpeace <strong>Renzi ostacola apertamente il diritto degli italiani a informarsi e a esprimersi consapevolmente il giorno del voto. E lo fa a loro spese, sprecando tra i 350 e i 400 milioni di euro di soldi pubblici. Tutto per scongiurare il quorum elettorale, svilire l&#8217;istituto referendario, avvantaggiare i petrolieri.<\/strong>\u00a0Andrea Boraschi, responsabile della campagna Energia e Clima di Greenpeace, dichiara: &#8220;Renzi, pur di fare cassa, aveva esordito vendendo auto blu su eBay. Ancora prima il PD, sempre per risparmiare risorse, aveva giustamente fatto pressione su Berlusconi per accorpare i referendum con le amministrative nel 2011. Oggi hanno cambiato verso. Fanno esattamente quanto fece il loro storico avversario, nel tentativo evidente di ridurre la partecipazione al voto. Il fatto \u00e8 che la maggioranza degli italiani \u00e8 contraria alle trivelle e Renzi lo sa bene&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Ogni minuto e luogo sono utili per invitare a votare il 17 aprile. <strong>I social come nel 2011, con il referendum contro il nucleare e per l&#8217;acqua pubblica, possono fare tanto. Possono fare tanto nel silenzio assordante dei media nazionali<\/strong>&#8220;. Cos\u00ec, in alcuni post su Facebook, il presidente del Consiglio regionale della Basilicata, Piero Lacorazza, che nel pomeriggio a Roma, dalle 15, incontrer\u00e0 &#8211; nella sede della Conferenza dei presidenti delle assemblee legislative &#8211; i rappresentanti dell&#8217;economia &#8220;green&#8221; e del mare, gli studenti, e i parlamentari, in relazione al referendum &#8220;anti trivelle&#8221;. &#8220;Non perdiamo nessuna occasione per chiedere di votare il 17 aprile, ha aggiunto Lacorazza, il quale ha poi &#8220;sollecitato&#8221; l&#8217;intervento della vigilanza Rai e l&#8217;Agicom in merito alla diffusione dei contenuti dei quesiti referendari.\u00a0Il Capo dello Stato Sergio Mattarella ha firmato ieri il decreto sulle norme in materia ambientale che indice il referendum popolare sulle trivelle.\u00a0Tra le prese di posizione pi\u00f9 recenti quella del deputato del M5s Roberto Fico secondo cui la decisione di fissare al 17 aprile la data del referendum sarebbe un tentativo del governo &#8221;di boicottarlo&#8221;. L&#8217;ultimo appello in ordine di tempo rivolto al Quirinale \u00e8 stato quello del presidente del consiglio regionale della Basilicata, Piero Lacorazza, che proprio ieri evidenziava come la data del 17 aprile indicata dal Governo avrebbe messo &#8221;a rischio l&#8217;applicazione della legge 28 del 2000 sulla par condicio&#8221;, perch\u00e8 questa data non consentirebbe &#8221;agli organi competenti di completare le procedure previste in tempo utile per far svolgere almeno 45 giorni di campagna elettorale, cosi&#8217; come prevede la legge&#8221;. E&#8217; di pochi giorni fa, infine, una lettera inviata a Mattarella da associazioni ambientaliste, sociali e studentesche e organizzazioni sindacali, comitati (tra i firmatari Legambiente, Wwf, Greenpeace e comitati del popolo &#8216;No-Triv&#8217;) in cui si chiedeva al presidente di &#8220;non firmare la deliberazione governativa&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Con una lettera indirizzata al presidente dell&#8217;Agcom, Marcello Cardani, e al presidente della Commissione parlamentare di Vigilanza Rai, Roberto Fico, il presidente del Consiglio regionale della Basilicata, Piero Lacorazza (Pd), ha sollecitato &#8220;l&#8217;intervento di questi organismi sulla questione della data del referendum&#8221; sulle trivelle. &#8220;Come certamente saprete &#8211; ha scritto &#8211; il Governo ha previsto di tenere la consultazione referendaria il 17 aprile 2016, cio\u00e8 fra 60 giorni a partire da oggi. In attesa della decisione che il presidente della Repubblica assumer\u00e0 a riguardo, mi permetto di sollecitare una vostra riflessione con riferimento alle procedure e al percorso concertativo che l<strong>&#8216;Autorit\u00e0 garante delle comunicazioni e la Commissione parlamentare di Vigilanza Rai, ognuna per le proprie competenze, sono chiamate a mettere in atto per garantire ai cittadini di essere informati sui quesiti oggetto del referendum abrogativo ed ai soggetti promotori del referendum, come pure agli eventuali comitati per il no, di far conoscere le proprie ragioni<\/strong>&#8220;. Secondo Lacorazza, &#8220;\u00e8 del tutto evidente che in un tempo cos\u00ec ristretto come quello previsto dal Governo sar\u00e0 molto difficile consentire lo svolgimento della campagna referendaria per almeno 45 giorni, cos\u00ec come prevede la normativa vigente. Tempo al quale occorre aggiungere quello necessario per l&#8217;espletamento di tutte le procedure di vostra competenza, che mi pare difficile possano essere completate in 15 giorni. Per questo motivo &#8211; ha evidenziato Lacorazza &#8211; vi chiedo di far sentire la vostra voce, intervenendo presso il Governo perch\u00e9 riveda la propria posizione, consentendo lo svolgimento del referendum in una data meno ravvicinata e compatibile con l&#8217;espletamento di tutte le procedure, comprese quelle relative alla programmazione dei messaggi autogestiti e degli spazi nelle tribune elettorali e nei programmi di informazione e di intrattenimento&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renzi tenta di boicottare la consultazione popolare per favorire le multinazionali del petrolio.<\/p>\n","protected":false},"author":22,"featured_media":52972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-52971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=52971"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/52971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/52972"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=52971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=52971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=52971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}