{"id":53087,"date":"2016-02-19T07:54:45","date_gmt":"2016-02-19T06:54:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/edilizia-e-sversamento-rifiuti-per-oliverio-valutare-limpatto-sullambientale-fa-perdere-tempo\/"},"modified":"2023-01-17T11:30:35","modified_gmt":"2023-01-17T10:30:35","slug":"76437-edilizia-e-sversamento-rifiuti-per-oliverio-valutare-limpatto-sullambientale-fa-perdere-tempo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/76437-edilizia-e-sversamento-rifiuti-per-oliverio-valutare-limpatto-sullambientale-fa-perdere-tempo\/","title":{"rendered":"Edilizia e sversamento rifiuti, per Oliverio valutare l&#8217;impatto sull&#8217;ambiente fa &#8216;perdere tempo&#8217;"},"content":{"rendered":"<p><strong>Capire se un impianto o una struttura pu\u00f2 nuocere alla salute pubblica non \u00e8 importante per il governatore della Regione Calabria.\u00a0<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">CATANZARO\u00a0&#8211; Il presidente della Regione Mario Oliverio, con apposito decreto, ha disposto l&#8217;adozione di misure urgenti per la velocizzazione della pratiche di autorizzazione in materia di valutazione di impatto ambientale (Via, Vas, Aia, Vi). <strong>A seguito di specifica ricognizione, effettuata nel febbraio 2015, e&#8217; emerso che le pratiche giacenti in attesa di autorizzazione al 31 dicembre 2014 erano 370 (Via, Aia) e circa 60 di Vas, per un importo di opere bloccate pari a oltre un miliardo di euro.<\/strong> Preso atto di tali criticita&#8217; all&#8217;interno del dipartimento Ambiente, si e&#8217; proceduto ad attuare misure urgenti finalizzate allo snellimento delle procedure. A seguito di tali correttivi, nel corso della ricognizione effettuata nel mese di gennaio 2016, e&#8217; emerso che il &#8220;trend&#8221; di evasione delle istanze e&#8217; passato da 20 pratiche, definite nel 2014, a 236, nel 2015. E&#8217; stato raggiunto un buon risultato ma non ancora soddisfacente. Con il decreto del 16 febbraio scorso &#8211; informa una nota dell&#8217;Ufficio stampa della Giunta &#8211; diventano ora operative le strutture temporanee di supporto all&#8217;evasione dell&#8217;arretrato delle pratiche Vas. <strong>L&#8217;adozione tempestiva e sinergica di tale misura potra&#8217; ragionevolmente consentire l&#8217;evasione in tempi rapidi di tutte le pratiche arretrate.<\/strong> Un passo importante per rimettere in moto una parte dell&#8217;economia regionale secondo la Giunta Oliverio, un pericoloso provvedimento che potrebbe mettere a rischio la salute pubblica di centinaia di cittadini invece per gli ambientalisti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capire se un impianto o una struttura pu\u00f2 nuocere alla salute pubblica non \u00e8 importante per il governatore della Regione Calabria.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":53088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-53087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53087"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53088"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}