{"id":53104,"date":"2016-02-19T12:38:33","date_gmt":"2016-02-19T11:38:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fincalabra-corte-dei-conti-segnala-danno-erariale-da\/"},"modified":"2023-01-17T11:30:37","modified_gmt":"2023-01-17T10:30:37","slug":"76763-fincalabra-corte-dei-conti-segnala-danno-erariale-da","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/76763-fincalabra-corte-dei-conti-segnala-danno-erariale-da\/","title":{"rendered":"Fincalabra e assunzioni illegittime, danno erariale da oltre 1,6 milioni"},"content":{"rendered":"<p><strong>A comunicarlo \u00e8 stato il procuratore regionale Rossella Scerbo, incontrando i giornalisti prima dell&#8217;inizio della cerimonia d&#8217;inaugurazione dell&#8217;anno giudiziario.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>CATANZARO &#8211; La Procura regionale della Corte dei Conti ha depositato una <strong>citazione<\/strong> nei confronti di <strong>Fincalabra<\/strong>, societa&#8217; in house della <strong>Regione Calabria,<\/strong> per un <strong>danno erariale<\/strong> di <strong>un milione e 613 mila euro<\/strong> &#8220;derivante da<strong> illegittime assunzioni di personale estern<\/strong>o&#8221;.\u00a0 Il procuratore ha aggiunto che attivita&#8217; istruttorie sono in corso su altri enti in house delle pubbliche amministrazioni calabresi.<\/p>\n<p>&#8220;Sono in corso accertamenti, con deleghe alla Guardia di Finanza, per svariate altre fattispecie di danno per spese, per ingenti importi, non rispondenti ai fini istituzionali, per assunzioni di personale in prossimita&#8217; di scadenza elettorali e conferimenti di incarichi e consulenze illegittime&#8221;.<\/p>\n<p>Il procuratore Scerbo proprio in tema di partecipate ha lanciato l&#8217;allarme. La<strong> riforma Madia<\/strong>, infatti, con un apposito decreto in fase di approvazione, prevede di &#8220;sottrarre alla magistratura contabile per affidarlo al giudice ordinario il potere di azione di responsabilita&#8217; nei confronti dei componenti degli organi di amministrazione e controllo delle societa&#8217; partecipate. Il rischio &#8211; a parere del magistrato &#8211; e&#8217; quello della compromissione della effettivita&#8217; della tutela delle risorse pubbliche&#8221;.<\/p>\n<p>Il procuratore ha voluto evidenziare l&#8217;impegno della Corte dei conti calabrese sugli illeciti nell&#8217;utilizzazione dei contributi europei per l&#8217;incremento dell&#8217;occupazione e la formazione di lavoratori svantaggiati. &#8220;Va sottolineata &#8211; ha detto &#8211; la gravita&#8217; dello sperpero delle risorse pubbliche che si attua secondo schemi ricorrenti, quali la mancata attivazione dei corsi di formazione, le assunzioni di soggetti privi dei requisiti di legge, a volte stretti congiunti o seguite da dimissioni forzate&#8221;. Il magistrato ha poi lamentato la &#8220;forte carenza di organico che si accentuera&#8217; &#8211; ha affermato &#8211; alla fine dell&#8217;anno se non dovessero intervenire fatti nuovi con l&#8217;arrivo di altri magistrati&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A comunicarlo \u00e8 stato il procuratore regionale Rossella Scerbo, incontrando i giornalisti prima dell&#8217;inizio della cerimonia d&#8217;inaugurazione dell&#8217;anno giudiziario.<\/p>\n","protected":false},"author":22,"featured_media":53105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-53104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53104"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53105"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}