{"id":53114,"date":"2016-02-19T14:40:48","date_gmt":"2016-02-19T13:40:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/76799\/"},"modified":"2023-01-17T11:30:38","modified_gmt":"2023-01-17T10:30:38","slug":"76799-76799","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/76799-76799\/","title":{"rendered":"Giovani democratici Cosenza, Rizzuti verso la riconferma"},"content":{"rendered":"<p><strong>Tutto \u00e8 pronto per il congresso, in programma per domani alle 15 presso la \u2018Sala Nova\u2019 all&#8217;interno del palazzo della provincia di Cosenza. L&#8217;unico candidato \u00e8 il segretario uscente, Michele Rizzuti. Per arrivare alla ricandidatura del segretario uscente, i GD che lo sostengono hanno diramato, tempo fa, un documento politico dettagliato, con in calce 67 firme.<\/strong><!--more--><br \/>\n&nbsp;<\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; \u201c<strong>Cosenza<\/strong> e la sua grande provincia &#8211; \u00e8 scritto nel documento dei <strong>Giovani democratici<\/strong> &#8211; sono il cuore pulsante del <strong>centrosinistra calabrese<\/strong>. Il territorio cosentino \u00e8 storia, presente e futuro del nostro partito e delle nostre comunit\u00e0. E questo ruolo centrale nello scenario regionale \u00e8 stato enfatizzato con l&#8217;operato di <strong>Michele Rizzuti<\/strong> alla guida dei giovani democratici cosentini. L&#8217;organizzazione giovanile provinciale ha svolto in pieno la sua funzione ed il suo compito di Avanguardia nei giovani democratici calabresi, sperimentando stagioni nuove ed innovative forme di partecipazione alla vita della giovanile\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201cNei confronti del <strong>Partito Democratico provinciale<\/strong> &#8211; riporta ancora la nota &#8211; continuiamo ad essere da stimolo, denunciando eventuali difficolt\u00e0 che riscontriamo sui territori, cercando di essere parte attiva nei processi di rinnovamento, pronti a responsabilizzare una nuova classe dirigente forgiata da anni di militanza nella nostra organizzazione. Il nostro lavoro \u00e8 stato, pertanto, un grande sforzo collettivo fatto da una grande comunit\u00e0 quale sono i giovani democratici della provincia di Cosenza, tenendo insieme i nostri militanti nel grande racconto romantico che ha contraddistinto la nostra azione ed il nostro agire. La storia dei giovani democratici cosentini \u00e8 la storia di tutti noi: sacrifici, battaglie, sconfitte e grandi successi\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201cLa nostra funzione pertanto non \u00e8 esaurita &#8211; conclude il comunicato dei Giovani democratici &#8211; ma va rilanciata nuovamente, oggi, pi\u00f9 di prima, perch\u00e9 siamo al governo della nazione, della regione e di moltissimi comuni. Il nostro ruolo \u00e8 determinante affinch\u00e9 la mole di lavoro svolta in questi anni non rimanga carta scritta ma diventi proposta per chi ci governa. Pertanto riteniamo che questo percorso debba essere guidato nuovamente dal Segretario Michele Rizzuti, perch\u00e9 la capacit\u00e0 di sintesi, di guida affiancate da onest\u00e0 intellettuale e lungimiranza politica dimostrate nel corso degli ultimi tre anni costituiscono un patrimonio per tutti noi giovani democratici cosentini. Proseguire il percorso con Segretario Michele Rizzuti \u00e8 per noi certezza di impegno continuo e di un ulteriore crescita per tutta la nostra organizzazione giovanile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutto \u00e8 pronto per il congresso, in programma per domani alle 15 presso la \u2018Sala Nova\u2019 all&#8217;interno del palazzo della provincia di Cosenza. L&#8217;unico candidato \u00e8 il segretario uscente, Michele Rizzuti. Per arrivare alla ricandidatura del segretario uscente, i GD che lo sostengono hanno diramato, tempo fa, un documento politico dettagliato, con in calce 67 [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":53115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-53114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53114"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53115"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}