{"id":53287,"date":"2016-02-24T08:51:04","date_gmt":"2016-02-24T07:51:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/muore-travolto-da-un-treno-in-corsa-tragedia-a-fuscaldo\/"},"modified":"2023-01-17T11:30:57","modified_gmt":"2023-01-17T10:30:57","slug":"77432-muore-travolto-da-un-treno-in-corsa-tragedia-a-fuscaldo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/77432-muore-travolto-da-un-treno-in-corsa-tragedia-a-fuscaldo\/","title":{"rendered":"Tragedia a Fuscaldo: 60enne travolto e ucciso da un treno in corsa"},"content":{"rendered":"<p><strong>La tragedia intorno alle 20.00\u00a0di ieri sera. Un 60enne\u00a0del posto,\u00a0Luigi Di Santo,\u00a0\u00e8 stato travolto da un treno in corso. Poco prima \u00e8 stato visto mentre camminava sul marciapiede che costeggia\u00a0i binari<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>FUSCALDO (CS) \u00a0&#8211; Un <strong>60enne<\/strong> di Fuscaldo,\u00a0Luigi Di Santo, \u00e8 moto ieri sera dopo essere stato travolto da un treno in corsa proprio all&#8217;altezza della stazione del centro tirrenico cosentino. L&#8217;uomo, molto conosciuto in paese\u00a0non era sposato e di lui si dice fosse\u00a0un gran lavoratore, una persona buona, allegra, che amava parlare di calcio, cantare anche se abbastanza solitaria. Ma quando c&#8217;era una\u00a0feste di paese partecipava sempre con molta allegria.<\/p>\n<p>Come raccontano alcuni <strong>residenti<\/strong>, aveva una situazione familiare non proprio facile, con una sorella malata e da tempo e costretta a letto. Di Santo,\u00a0che per molti anni ha lavorato al nord Italia alla <strong>costruzione<\/strong> di gallerie, aveva una corporatura esile e proprio prima della tragedia \u00e8 stato visto dirigersi in direzione della stazione mentre mangiava un panino, aveva in mano una birra e camminava lungo il <strong>marciapiede<\/strong> che costeggia i binari. Per questo le prime ipotesi fanno pensare ad una tragica fatalit\u00e0 e non ad un tentativo di suicidio. Nonostante la celerit\u00e0 dei soccorsi con\u00a0l&#8217;arrivo del <strong>118<\/strong> e della <strong>forze dell&#8217;ordine<\/strong> per l&#8217;uomo\u00a0non c&#8217;\u00e8 stato nulla da fare. Di Santo, trascinato per diversi metri \u00e8 morto sul colpo. Per diverse ore la linea ferroviaria tirrenica \u00e8 stata bloccata con ripercussioni sul traffico ferroviario e ritardi anche di alcune ore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tragedia intorno alle 20.00\u00a0di ieri sera. Un 60enne\u00a0del posto,\u00a0Luigi Di Santo,\u00a0\u00e8 stato travolto da un treno in corso. Poco prima \u00e8 stato visto mentre camminava sul marciapiede che costeggia\u00a0i binari<\/p>\n","protected":false},"author":22,"featured_media":53288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-53287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53287"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53288"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}