{"id":53369,"date":"2016-02-25T16:06:03","date_gmt":"2016-02-25T15:06:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/le-riserve-del-lago-di-tarsia-e-della-foce-del-crati-in-onda-su-rai-3\/"},"modified":"2023-01-17T11:31:05","modified_gmt":"2023-01-17T10:31:05","slug":"77749-le-riserve-del-lago-di-tarsia-e-della-foce-del-crati-in-onda-su-rai-3","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/77749-le-riserve-del-lago-di-tarsia-e-della-foce-del-crati-in-onda-su-rai-3\/","title":{"rendered":"Le Riserve del Lago di Tarsia e della Foce del Crati in onda su Rai 3"},"content":{"rendered":"<p><strong>Il \u201cTesoro di Alarico\u201d \u00e8 \u00a0il titolo dato dalla redazione di Geo al servizio che parler\u00e0 dello straordinario patrimonio delle Riserve, in onda su Rai 3 domani\u00a0alle 17,30 circa.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">TARSIA (CS) &#8211; La trasmissione condotta da <strong>Sveva Sagramola<\/strong> e da <strong>Emanuele Biggi<\/strong> porter\u00e0 a conoscere una delle pi\u00f9 importanti aree umide del meridione d\u2019Italia, punto di sosta e di approvvigionamento trofico per migliaia di uccelli migratori, e luogo con un&#8217;interessante vegetazione, con l\u2019ultimo tratto di fiume ricoperto a bosco planiziale, relitto di una vegetazione che un tempo ricopriva tutta la piana.\u00a0Per la straordinaria e diversificata biodiversit\u00e0 animale e vegetale che custodiscono, le <strong>Riserve<\/strong> sono sempre pi\u00f9 attrattori di naturalisti, ricercatori e amanti della natura e finiscono per stupire appassionati ed esperti.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Un ambiente che ha suscitato l\u2019interesse di <strong>Francesco Petretti<\/strong>, naturalista ed ornitologo e <strong>Francesca Catarci<\/strong>, documentarista e regista di Rai 3, per come si evince dal comunicato del reportage \u201c\u2026 dalle montagne del Pollino alla sua foce nel lungo e silenzioso litorale ionico, il <strong>fiume Crati<\/strong> scorre fra boschi agrumeti e risaie di una Calabria poco nota e rivela al nostro naturalista Francesco Petretti seguito dalla troupe di <strong>Geo<\/strong> diretta da Francesca Catarci lo splendore di una foce assolutamente naturale in cui la corrente del fiume si unisce alle acque del mare fra il volo degli uccelli migratori\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il \u201cTesoro di Alarico\u201d \u00e8 \u00a0il titolo dato dalla redazione di Geo al servizio che parler\u00e0 dello straordinario patrimonio delle Riserve, in onda su Rai 3 domani\u00a0alle 17,30 circa.<\/p>\n","protected":false},"author":22,"featured_media":53370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,13],"tags":[],"class_list":["post-53369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53369"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53370"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}