{"id":53426,"date":"2016-02-26T15:53:49","date_gmt":"2016-02-26T14:53:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sette-comuni-del-cosentino-inaugurano-lisola-ecologica\/"},"modified":"2023-01-17T11:31:12","modified_gmt":"2023-01-17T10:31:12","slug":"77912-sette-comuni-del-cosentino-inaugurano-lisola-ecologica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/77912-sette-comuni-del-cosentino-inaugurano-lisola-ecologica\/","title":{"rendered":"Sette comuni del cosentino inaugurano l&#8217;isola ecologica"},"content":{"rendered":"<p><strong>Domani mattina, alle 11,00, sar\u00e0 inaugurato\u00a0il centro di raccolta a supporto della differenziata.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">MENDICINO (CS) &#8211; L&#8217;isola ecologica \u00e8 a disposizione dei cittadini e dei comuni di Mendicino, Carolei, Dipignano, Domanico, Cerisano, Marano Principato e Marano Marchesato.\u00a0Un servizio che coinvolge circa 30 mila abitanti e che \u00e8 collocato sul territorio di Mendicino, in <strong>via Acherunzia<\/strong>.\u00a0&#8220;L&#8217;isola ecologica intercomunale \u00e8 un ulteriore passo avanti verso l&#8217;unione dei territori e dei servizi a favore di tutti i cittadini di questo vasto comprensorio. Un grande apporto al ciclo dei rifiuti ed un aiuto concreto al potenziamento della<strong> raccolta differenziata<\/strong>, al fine di ottenere percentuali ancora pi\u00f9 elevate&#8221;, afferma il sindaco di Mendicino,<strong> Antonio Palermo<\/strong>, capofila del progetto. &#8220;L&#8217;obiettivo dei primi cittadini \u00e8 quello di unire sforzi, intenti, progettualit\u00e0 e modi d&#8217;operare per far crescere sinergicamente i territori&#8221;.\u00a0All&#8217;iniziativa sar\u00e0 presente, con i sindaci dei sette Comuni, anche il presidente della Regione Calabria Mario Oliverio.\u00a0Il progetto \u00e8 stato realizzato oltre che con risorse dei singoli Comuni anche con fondi regionali del Por Calabria provenienti dall&#8217;Unione europea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani mattina, alle 11,00, sar\u00e0 inaugurato\u00a0il centro di raccolta a supporto della differenziata.<\/p>\n","protected":false},"author":22,"featured_media":53427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,13],"tags":[],"class_list":["post-53426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53426"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53427"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}