{"id":53476,"date":"2016-02-28T06:20:39","date_gmt":"2016-02-28T05:20:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-tasse-alle-stelle-mancate-bonifica-protesta-domani-municipio\/"},"modified":"2023-01-17T11:31:18","modified_gmt":"2023-01-17T10:31:18","slug":"78078-rende-tasse-alle-stelle-mancate-bonifica-protesta-domani-municipio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/78078-rende-tasse-alle-stelle-mancate-bonifica-protesta-domani-municipio\/","title":{"rendered":"Rende tasse alle stelle e mancate bonifica, protesta domani in municipio"},"content":{"rendered":"<p><strong>Cittadini chiamati a manifestare Luned\u00ec mattina davanti il Comune di Rende.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE &#8211; Domani Luned\u00ec 29 Febbraio sit &#8211; in di protesta a Rende a partire dalle 10.30 presso il municipio. L&#8217;associazione amibientalista Crocevia sollecita i i cittadini a manifestare in piazza Rossini davanti all&#8217;ingresso del Comune di Rende per chiedere che i propri diritti vengano rispettati. La mobilitazione \u00e8 stata indetta per sollecitare la Giunta Manna ad attuare provvedimenti al fine di avviare la bonifica dell&#8217;ex Legnochimica di contrada Lecco e dell&#8217;area del depuratore di Coda di Volpe. Gli attivisti chiedono inoltre che il sindaco si occupi di rivedere le tariffe sulla Tari aumentate notevolmente rispetto agli anni passati. Nel corso della mattinata sino alle 13.00 sar\u00e0 possibile partecipare attivamente alla protesta e reperire informazioni in merito allo stato dell&#8217;arte delle priorit\u00e0 del territorio rendese e della sua\u00a0cittadinanza. I manifestanti chiederanno inoltre chiarimenti in merito alle denunce presentate per chiedere che l&#8217;autorit\u00e0 giudiziaria si attivi per risalire alla causa delle esalazioni maleodoranti che invadono i quartieri da Contrada Lecco a Commenda.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/430\">CLICCA QUI PER<\/a><\/h3>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/430\">Le critiche al sistema di Tassazione sui rifiuti del Comune di Rende<\/a><\/h3>\n<h3 style=\"text-align: left;\"><strong><a href=\"https:\/\/quicosenza.it\/news\/431\">I cattivi odori a Rende, la denuncia dei residenti<\/a><\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cittadini chiamati a manifestare Luned\u00ec mattina davanti il Comune di Rende.<\/p>\n","protected":false},"author":22,"featured_media":53477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-53476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53476"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53477"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}