{"id":53863,"date":"2016-03-09T06:17:36","date_gmt":"2016-03-09T05:17:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/discarica-celico-oliverio-ignora-la-presila-attivisti-annunciano-blocco\/"},"modified":"2023-01-17T11:32:03","modified_gmt":"2023-01-17T10:32:03","slug":"79651-discarica-celico-oliverio-ignora-la-presila-attivisti-annunciano-blocco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/79651-discarica-celico-oliverio-ignora-la-presila-attivisti-annunciano-blocco\/","title":{"rendered":"Discarica di Celico: Oliverio ignora la Presila, attivisti annunciano blocco"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Mobilitazione popolare a partire da domani mattina contro la Mi.Ga. di Raffaele Vrenna.<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">COSENZA &#8211; Anche la scorsa domenica il Presidente della Regione Calabria Mario Oliverio ha disertato l&#8217;incontro con la popolazione della Presila.\u00a0Insieme ai pochi amministratori presenti, il Comitato Ambientale Presilano ha quindi deciso di concerto di avviare una campagna di mobilitazione popolare.\u00a0<strong>\u00c9 la politica che ha voluto aprire la discarica illegale di Celico e dovr\u00e0 essere la politica a chiuderla.<\/strong>\u00a0Come al solito gli serve una spinta, per cui tocca alla cittadinanza difendere il proprio territorio e il proprio futuro.\u00a0Il primo appuntamento \u00e8 per gioved\u00ec 10 Marzo alle 7.00 di mattinata, presso lo svincolo ss 107 a Spezzano Sila in localit\u00e0 Petramuni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mobilitazione popolare a partire da domani mattina contro la Mi.Ga. di Raffaele Vrenna.<\/p>\n","protected":false},"author":22,"featured_media":53864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-53863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53863"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53864"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}