{"id":53879,"date":"2016-03-08T11:06:27","date_gmt":"2016-03-08T10:06:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/latitante-narcotraffico-fiumicino-arresto\/"},"modified":"2023-01-17T11:32:05","modified_gmt":"2023-01-17T10:32:05","slug":"79701-latitante-narcotraffico-fiumicino-arresto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/79701-latitante-narcotraffico-fiumicino-arresto\/","title":{"rendered":"Scomparso da cinque anni, narcotrafficante viene rintracciato dalle autorit\u00e0"},"content":{"rendered":"<p><strong>L&#8217;uomo \u00e8 stato bloccato da carabinieri mentre rientrava in Italia da un viaggio in Australia.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">LOCRI (RC)\u00a0&#8211; Il latitante Antonio Vottari, 31 anni, ricercato da cinque anni \u00e8 stato arrestato stamattina a Roma. L&#8217;uomo, al termine di indagini condotte anche dai militari di San Luca, \u00e8 stato bloccato all&#8217;aeroporto di Fiumicino dove \u00e8 giunto dall&#8217;Australia. Condannato il 30 settembre scorso ad una pena definitiva di 7 anni e 6 mesi di reclusione, Vottari \u00e8 ritenuto responsabile di aver fatto parte di un&#8217;associazione finalizzata al traffico internazionale di ingenti quantitativi di cocaina, operante tra Sudamerica, Olanda, Belgio, Germania e Italia, e gestito dalle cosche di San Luca. Gi\u00e0 condannato nel 2004 per reati in materia di stupefacenti, era ricercato dal 2011 dopo che nei suoi confronti era stata emessa un&#8217;ordinanza cautelare dal gip di Reggio Calabria per traffico internazionale di stupefacenti. <strong>Nei suoi confronti era stato anche emesso un mandato di cattura europeo.<\/strong> Al vertice dell&#8217;organizzazione criminale vi era Bruno Pizzata 57enne condannato per narcotraffico a 30 anni di reclusione. Pizzata, intercettato per diversi anni dalle forze di polizia italiane, dal Bka (la Polizia Criminale Tedesca) e dalla Polizia Federale Olandese, \u00e8 ritenuto il capo di varie associazioni che hanno trafficato droga tra il Sudamerica e l&#8217;Europa. Tra il 2010 ed il 2013, Pizzata \u00e8 stato destinatario di provvedimenti cautelari emessi nell&#8217;ambito delle operazioni antidroga denominate &#8220;Overloading&#8221;, &#8220;Imelda&#8221;, &#8220;Revolution&#8221;, &#8220;Dionisio&#8221; e &#8220;Cicala&#8221; coordinate dalle Direzioni distrettuali antimafia di Catanzaro e Reggio Calabria, nel corso delle quali sono stati sequestrati centinaia di chili di cocaina importata dal Centro e dal Sudamerica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo \u00e8 stato bloccato da carabinieri mentre rientrava in Italia da un viaggio in Australia.<\/p>\n","protected":false},"author":22,"featured_media":53880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22,571],"tags":[],"class_list":["post-53879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=53879"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/53879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/53880"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=53879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=53879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=53879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}