{"id":54018,"date":"2016-03-10T16:25:01","date_gmt":"2016-03-10T15:25:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lantica-grecia-bronzi-riace-raccontati-rai5\/"},"modified":"2023-01-17T11:32:21","modified_gmt":"2023-01-17T10:32:21","slug":"80191-lantica-grecia-bronzi-riace-raccontati-rai5","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/80191-lantica-grecia-bronzi-riace-raccontati-rai5\/","title":{"rendered":"L&#8217;antica Grecia e i Bronzi di Riace raccontati su Rai5"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>L&#8217;evoluzione dell&#8217;arte greca da un passato remoto fino al VI secolo avanti Cristo.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">RIACE (RC) &#8211; Lo racconta Simon Alastair Sooke, critico d&#8217;arte e giornalista, protagonista di &#8220;I tesori dell&#8217;antica Grecia&#8221; che Rai Cultura propone a partire da oggi\u00a0alle 18.45 su Rai5. Nell&#8217;agosto del 1972 un sub stava esplorando i fondali del Mediterraneo lungo le coste dell&#8217;Italia meridionale. A sette metri di profondit\u00e0 scorse una mano emergere dalla sabbia; la tocc\u00f2 e si accorse che il mare stava restituendo due statue sepolte chiss\u00e0 quanto tempo prima. Si trattava di due magnifici <strong>guerrieri di bronzo<\/strong>, riproduzione perfetta di due uomini di 500 anni prima di Cristo: nudi, atletici, perfetti, realizzati grazie alla padronanza assoluta di tecniche e conoscenze raffinatissime, in un tempo in cui gran parte degli abitanti del Nord Europa ancora viveva in capanne primitive. Da Riace, Simon Sooke, analizza l&#8217;evoluzione dell&#8217;eccellenza degli artisti greci rispetto al secolo precedente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;evoluzione dell&#8217;arte greca da un passato remoto fino al VI secolo avanti Cristo.<\/p>\n","protected":false},"author":22,"featured_media":54019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-54018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=54018"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54019"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=54018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=54018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=54018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}