{"id":54110,"date":"2016-03-12T14:00:55","date_gmt":"2016-03-12T13:00:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/diretta-live-cosenza-paganese-0-0-la-gara-dei-rossoblu-tempo-reale\/"},"modified":"2023-01-17T11:32:31","modified_gmt":"2023-01-17T10:32:31","slug":"80525-diretta-live-cosenza-paganese-0-0-la-gara-dei-rossoblu-tempo-reale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/80525-diretta-live-cosenza-paganese-0-0-la-gara-dei-rossoblu-tempo-reale\/","title":{"rendered":"Il Cosenza sbatte sul muro della Paganese e Cavallaro sbaglia un rigore. Finisce 0 a 0"},"content":{"rendered":"<p><strong>Partita non bellissima ma dominata dal Cosenza che per\u00f2 trovano nella difesa della Paganese un muro insuperabile. Nel secondo tempo l&#8217;occasione capita sui piedi di Cavallaro a 10 minuti dal termine, ma l&#8217;ex Foggia manda fuori un calcio di rigore<\/strong><br \/>\n<!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Mezzo passo falso del Cosenza che raccoglie solo un punto in casa nel match contro la Paganese e per la seconda volta in questo campionato resta a secco di reti al Marulla. Rossoblu che hanno provato in pi\u00f9 occasioni a scardinare il muro difensivo eretto dai campani ma senza riuscirci, vuoi per la poca precisione dei suoi attaccanti, vuoi per il terreno reso pesante dalla pioggia vuoi anche per un paio di interventi miracolosi di <strong>Maruocco<\/strong>, sopratutto nella prima frazione di gara.\u00a0A dire il vero l&#8217;occasione giusta il Cosenza l&#8217;ha\u00a0trovata a\u00a010 minuti dal termine quando <strong>Ciancio<\/strong>, dopo una serpentina in area di rigore, viene\u00a0steso da <strong>Sirignano<\/strong>. Per il <strong>signor Prontera<\/strong> di Bologna \u00e8 calcio di rigore nonostante le veementi proteste ospiti. Sul dischetto si presenta <strong>Cavallaro<\/strong> che spiazza Marruocco ma spara incredibilmente fuori. Pareggio che complica la rincorsa del Cosenza alle zone altissime di classifica.<\/p>\n<p>Il<strong> primo tempo\u00a0<\/strong>inizia con ritmi lenti, anche a causa delle condizioni del terreno reso pesante dalle piogge degli ultimi giorni e con il Cosenza che prova a far girare la palla per trovare qualche spazio nella arretratissima difesa della Paganese che\u00a0preferisce starsene\u00a0rintanata nella propria met\u00e0 campo affidandosi di tanto in tanto alle ripartenze di <strong>Cunzi<\/strong> e <strong>Caccavallo<\/strong>. L&#8217;occasione migliore capita sulla testa di <strong>La Mantia<\/strong> che servito da un assist perfetto di Corsi gira verso l&#8217;angolo lontano ma Marruocco vola a deviare il pallone. il Cosenza prova a spingere e scodella in area campana diversi palloni che creano apprensione alla retroguardia della Paganese costretta spesso a spazzare in fallo laterale.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/506\" rel=\"attachment wp-att-80721\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80721\" src=\"https:\/\/quicosenza.it\/news\/506\" alt=\"Cosenza Paganese06\" width=\"618\" height=\"412\" title=\"\"><\/a><\/p>\n<p><b>Nel secondo tempo <\/b>il Cosenza prova a spingere il piede\u00a0sull&#8217;acceleratore\u00a0e stringe d&#8217;assedio la retroguardia della Paganese che barcolla ma non crolla. Ci prova prima <strong>Statella<\/strong> (sottotono la sua gara) dalla distanza senza esito, poi su un pallone deviato anche Tedeschi che svirgola a pochi metri dalla porta. Alla prima occasione da rete la Paganese rischia di passare con\u00a0Della Corte che lascia partite un siluro dalla distanza disinnescato da Perina e dal palo. Roselli le prova tutte inserendo Cavallaro, <strong>Ciancio<\/strong> e <strong>Vutov<\/strong> ma gli spazi sono sempre pi\u00f9 chiusi e non bastano decine e decine di palloni messi in area per sbloccare la rete. Ci vorrebbe l&#8217;invenzione di un singolo, che arriva a 10 minuti dal termine con Ciancio\u00a0che sembra Alberto Tomba dei tempi belli e salta in dribbling 3 avversari, entra in area e viene toccato da dietro da <strong>Sirignano<\/strong>: \u00e8 rigore per il Cosenza nonostante le proteste della Paganese. Sul dischetto si presenta Cavallaro che dopo aver confabulato per la battuta del penalty con <strong>La Mantia<\/strong>, calcia clamorosamente fuori. In prativa la gara finisce qui perch\u00e9\u00a0negli ultimi 10 minuti si gioca poco a calcio e pi\u00f9 a calci. Una battuta d&#8217;arresto\u00a0che complica non poco i piani dei rossoblu che rischiano di vedere scappare le altre squadre.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>VIDEO MATCH<\/strong><\/span><br \/>\n<iframe loading=\"lazy\" src=\"http:\/\/sportube.tv\/embed?id=17862\" width=\"640\" height=\"480\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/507\" rel=\"attachment wp-att-49952\"><br \/>\n<\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-49952\" src=\"https:\/\/quicosenza.it\/news\/507\" alt=\"Cosenza Calcio logo\" width=\"113\" height=\"147\" title=\"\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/quicosenza.it\/news\/508\" rel=\"attachment wp-att-49958\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38498 alignnone\" src=\"https:\/\/quicosenza.it\/news\/508\" alt=\"Paganese Calcio 1926 Logo\" width=\"121\" height=\"134\" title=\"\"><\/a><\/p>\n<p style=\"text-decoration: blink;\"><span style=\"font-family: 'arial black', 'avant garde'; font-size: 18pt;\"><strong style=\"font-size: 18px; line-height: 1;\"><span style=\"font-size: 18pt;\"><span style=\"color: #000000; text-decoration: blink;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cosenza \u00a0&#8211;\u00a0<\/span><span style=\"color: #ff0000; text-decoration: blink;\"><span style=\"color: #000000; text-decoration: blink;\"> Paganese<\/span><\/span><\/span><\/strong><\/span><\/p>\n<div id=\"blink\" style=\"text-align: center;\"><span style=\"color: #ff0000; font-size: 20pt;\"><a target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">\u00a0 \u00a0 0\u00a0&#8211;\u00a00<\/span><\/a><\/span><\/div>\n<p><span style=\"color: #000000;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Marcatori<\/strong>: <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\">PRIMO TEMPO<\/span><br \/>\n<\/span><\/strong><span style=\"color: #000000;\">Squadre che fanno il loro ingresso in campo davanti a poco pi\u00f9 di 1.800 tifosi. Cosenza nella classica tenuta rossoblu. Ospiti in divisa completamente bianca<br \/>\n<strong style=\"color: #000000;\">1&#8242; &#8211;<\/strong>\u00a0La Paganese da il via alla gara. Rossoblu che in questa prima frazione attaccheranno verso la Curva Sud Donato Bergamini<br \/>\n<strong style=\"color: #000000;\">3&#8242; &#8211;<\/strong>\u00a0La\u00a0Mantia verticalizza per Arrighini, Sirignano\u00a0in extremis ci\u00a0mette il piede e manda la palla in angolo<br \/>\n<strong style=\"color: #000000;\">5&#8242; &#8211;<\/strong>\u00a0Si vede la Paganese che prova la conclusione da lontanissimo con Carcione,\u00a0che ciabatta di\u00a0destro e spedisce fuori<br \/>\n<strong style=\"color: #000000;\">10&#8242; &#8211;<\/strong>\u00a0Sono andati via i primi 10 minuti di gara. Ritmi accettabili, anche se non velocissimi per ora e\u00a0Cosenza\u00a0che prova a fare la gara con la Paganese che gioca di rimessa<br \/>\n<strong style=\"color: #000000;\">11&#8242; &#8211;<\/strong>\u00a0Proteste della Paganese per un presunto contatto in area tra Pinna e Cunzi con il signor Prontera che fa segno di proseguire. Dall&#8217;altra parte Criaco mete un pallone al centro dell&#8217;area per la testa di La Mantia anticipato da Marruoco con i pugni<br \/>\n<strong style=\"color: #000000;\">20&#8242; &#8211;<\/strong>\u00a0Paganese che si difende con ordine e Cosenza che fatica a creare azioni da rete pericolose<br \/>\n<strong style=\"color: #000000;\">23&#8242; &#8211;<\/strong>\u00a0Cross di Pinna dalla sinistra e spettacolare colpo di tacco al volo di La Mantia. Marruocco \u00e8 attento e <\/span><span style=\"color: #000000;\">blocca il pallone a terra<br \/>\n<strong style=\"color: #000000;\">30&#8242; &#8211;<\/strong>\u00a0Mezzora di gioco e gara che stenta a decollare con le due formazioni che trotterellano in campo<br \/>\n<strong style=\"color: #000000;\">31&#8242; &#8211;<\/strong>\u00a0Occasionissima da rete per il Cosenza. Cross tagliato di Corsi dalla destra per il colpo di testa di La Mantia\u00a0che indirizza sul secondo palo, Marruocco \u00e8 miracoloso a deviare il pallone con la mano destra<br \/>\n<strong style=\"color: #000000;\">37&#8242; &#8211;<\/strong>\u00a0Ancora rossoblu pericolosi: pallone al bacio in aera\u00a0di Fiordilino per Arrighini che invece di calciare verso la porta, prova un improbabile assist per La Mantia e l&#8217;azione sfuma<br \/>\n<strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/398\" rel=\"attachment wp-att-38926\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/398\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\"><\/a>40&#8242; &#8211;<\/strong>\u00a0Ammonito Di Nunzio per un fallo su Caccavallo<br \/>\n<strong style=\"color: #000000;\">44&#8242; &#8211;<\/strong>\u00a0Rossoblu che ad ogni pallone scodellato in area mettono apprensione alla retroguardia campana costretta spesso a spazzare in fallo laterale<br \/>\n<strong style=\"color: #000000;\">45&#8242; &#8211;<\/strong>\u00a0<strong>Finale 1 tempo<\/strong>.\u00a0Non c&#8217;\u00e8 recupero. Cosenza e Paganese vanno la riposo sullo 0 a 0<br \/>\n<\/span><\/p>\n<p><strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\">SECONDO\u00a0TEMPO<br \/>\n<strong style=\"color: #000000;\">46&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Riparte la ripresa. Nessun cambio nell&#8217;intervallo e stessi 22 in campo<br \/>\n<strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/398\" rel=\"attachment wp-att-38926\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/398\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\"><\/a>47&#8242; &#8211;<\/strong>\u00a0Ammonito Tedeschi dopo una brutta entrata su Cunzi<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">49&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Cunzi dal vertice sinistro prova la conclusione ma Perina \u00e8 attento e blocca a terra<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">50&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Corner battuto da Arrigoni, sulla respinta della difesa si avventa Criaco che prova il destro al volo che finisce alle stesse<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">51&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Ancora Cosenza pericoloso con Statella che salta un difensore e dal limite prova il destro ma il tiro \u00e8 debole e Marruocco blocca a terra<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/398\" rel=\"attachment wp-att-38926\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/398\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\"><\/a>52&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Ammonito Carcione per un fallo su Criaco in ripartenza<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/399\" rel=\"attachment wp-att-38354\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/399\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\"><\/a>55&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Arriva il primo cambio della gara per il Cosenza. Roselli butta nella mischia Cavallaro che rileva Statella<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">58&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Paganese ad un passo dalla rete con una conclusione dalla distanza di Della Corte\u00a0sulla quale Perina arriva e deviare il pallone che rimbalza sul palo<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/399\" rel=\"attachment wp-att-38354\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/399\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\"><\/a>63&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Secondo cambio per Roselli. Fuori Criaco che lascia il posto a Simone Ciancio<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">65&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Sinistro a giro di Caccavallo sul secondo palo. Perina si tuffa e blocca a terra<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">69&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Uscite spericolata di Perina che per poco non combina la frittata. Sull&#8217;intervento del portiere rossoblu alla kamikaze rimangono due giocatori della Paganese a terra e si accende una mischia sedata a fatica dall&#8217;arbitro<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/399\" rel=\"attachment wp-att-38354\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/399\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\"><\/a>70&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Terzo e ultimo cambio per il Cosenza. Vutov in campo al posto di Corsi<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">74&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Cross di Pinna per La Mantia che per un soffio manca il pallone che si spegne sul fondo<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/399\" rel=\"attachment wp-att-38354\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/399\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\"><\/a>77&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Primo cambio per la Paganese. Fuori Caccavallo e dentro Parente<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">78&#8242; -Rigore per il Cosenza. Fallo in area di Sirignano su\u00a0Ciancio<br \/>\n<strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/398\" rel=\"attachment wp-att-38926\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38926 alignnone\" src=\"https:\/\/quicosenza.it\/news\/398\" alt=\"Ammonizione\" width=\"18\" height=\"24\" title=\"\"><\/a>78&#8242; &#8211;<\/strong><\/strong><\/span><\/span><\/strong>\u00a0Ammonito Esposito\u00a0per proteste<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\">79&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><span style=\"color: #ff0000;\">Batte Cavallaro e incredibilmente spedisce la palla fuori alla destra di Marruocco che si era buttato dall&#8217;altra parte. Si rimane sullo 0 a 0<br \/>\n<strong style=\"color: #000000;\">85&#8242; &#8211;<\/strong>\u00a0<\/span><\/strong><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Ultimi 5 minuti della gara con il Cosenza che prova il forcing finale. Paganese raccolta tutta dietro<br \/>\n<strong><span style=\"color: #000080;\"><span style=\"color: #0000ff;\"><strong style=\"color: #000000;\"><a href=\"https:\/\/quicosenza.it\/news\/399\" rel=\"attachment wp-att-38354\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38354 alignnone\" src=\"https:\/\/quicosenza.it\/news\/399\" alt=\"Sostituzione\" width=\"30\" height=\"20\" title=\"\"><\/a>89&#8242; &#8211;<\/strong>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">Sostituzione Paganese. Fuori Cunzi e dentro Vella<br \/>\n<strong><strong style=\"color: #000000;\">90&#8242; &#8211;<\/strong>\u00a0<\/strong><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Ci saranno solo 3 minuti\u00a0di recupero, Rumoreggia il Marulla<br \/>\n<strong><strong style=\"color: #000000;\">93&#8242; &#8211;<\/strong>\u00a0<span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Finale. Cosenza e Paganese 0 a 0.<\/span><\/span><\/strong><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><strong><br \/>\n<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #ffffff;\">.<\/span><\/strong><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<br \/>\n<\/strong><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Cosenza Calcio (4-4-2): <\/strong>Perina, Di Nunzio, Pinna, Corsi (70&#8242; Corsi), Arrigoni, Tedeschi, Criaco (63&#8242; Ciancio), Caccetta, Arrighini, La Mantia, Statella(60&#8242; Cavallaro)<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina:<\/strong> Saracco, Corsi\u00a0Di Somma, Ciancio, Cavallaro, Minardi, Parigi, Ventre, Vutov<strong><br \/>\n<strong>Allenatore<\/strong>: <\/strong>Giorgio Roselli<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Paganese\u00a0Calcio (4-3-3): <\/strong>Marruocco; Dozi, Sirignano, Bocchetti, Della Corte; Guerri, Carcione, Palmiero, Caccavallo (77&#8242; Parente), Cunzi (89&#8242; Vella), Cella<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina<\/strong>: Maione, Acampora, Penna, Parente, Magri, Cassata, <span id=\"more-22253\"><\/span>, Grillo, Tommasone, Cicerelli<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Allenatore<\/strong>:\u00a0Gianluca Grassadonia<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Arbitro<\/strong>: Signor\u00a0Emiliano Prontera di Bologna<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Assistenti: <\/strong>Signor\u00a0Nicola Nevio Spiniello e signor\u00a0Alessandro Iovine di Napoli<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Ammoniti<\/strong>: Di Nunzio (C), Tedeschi(C), Carcione (P), Esposito (P)<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Espulsi<\/strong>:<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Angoli<\/strong>: 6-4<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #000000;\"><strong>Note<\/strong>:\u00a0Giornata fredda e piovosa. Terreno allentato dalle piogge degli ultimi giorni ma in discrete condizioni. Spettatori presenti al Marulla 1.879 (1377 paganti +\u00a0422 abbonati) per un incasso di\u00a013.277\u00a0\u20ac. Nessun tifoso ospite<\/span><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/509\" rel=\"attachment wp-att-80617\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80617\" src=\"https:\/\/quicosenza.it\/news\/509\" alt=\"Cosenza Paganese_tifosi\" width=\"623\" height=\"271\" title=\"\"><\/a><\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80635 \" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/03\/Cosenza-Paganese01.jpg\" alt=\"\" width=\"635\" height=\"357\" title=\"\"><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/510\" rel=\"attachment wp-att-80722\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80722\" src=\"https:\/\/quicosenza.it\/news\/510\" alt=\"Cosenza Paganese06\" width=\"612\" height=\"408\" title=\"\"><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/511\" rel=\"attachment wp-att-80723\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80723\" src=\"https:\/\/quicosenza.it\/news\/511\" alt=\"Cosenza Paganese07\" width=\"602\" height=\"403\" title=\"\"><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/512\" rel=\"attachment wp-att-80724\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80724\" src=\"https:\/\/quicosenza.it\/news\/512\" alt=\"Cosenza Paganese08\" width=\"600\" height=\"400\" title=\"\"><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/quicosenza.it\/news\/513\" rel=\"attachment wp-att-80725\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-80725\" src=\"https:\/\/quicosenza.it\/news\/513\" alt=\"Cosenza Paganese09\" width=\"591\" height=\"395\" title=\"\"><\/a><\/p>\n<p style=\"text-align: left;\">\n","protected":false},"excerpt":{"rendered":"<p>Partita non bellissima ma dominata dal Cosenza che per\u00f2 trovano nella difesa della Paganese un muro insuperabile. Nel secondo tempo l&#8217;occasione capita sui piedi di Cavallaro a 10 minuti dal termine, ma l&#8217;ex Foggia manda fuori un calcio di rigore<\/p>\n","protected":false},"author":23,"featured_media":54111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-54110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=54110"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/54110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/54111"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=54110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=54110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=54110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}